{"id":5643,"date":"2024-04-25T16:01:40","date_gmt":"2024-04-25T14:01:40","guid":{"rendered":"https:\/\/infinitteurope.com\/rt-pacs\/"},"modified":"2025-06-24T10:46:49","modified_gmt":"2025-06-24T08:46:49","slug":"rt-pacs","status":"publish","type":"page","link":"https:\/\/infinitteurope.com\/pl\/rt-pacs\/","title":{"rendered":"RT PACS"},"content":{"rendered":"<div id='av_section_1'  class='avia-section av-lrqbb6pj-95fac9e02e89b7917a2ab23226927d2d main_color avia-section-default avia-no-border-styling  avia-builder-el-0  el_before_av_section  avia-builder-el-first  intro-product avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-5643'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-1h5gnr-6198feac3ccb257dc2077f0df6108162 av_one_half  avia-builder-el-1  el_before_av_one_half  avia-builder-el-first  first flex_column_div  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1aj4ev-3c0772d617fe2ec36c9507fbb665b38b\">\n.avia-image-container.av-1aj4ev-3c0772d617fe2ec36c9507fbb665b38b img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-1aj4ev-3c0772d617fe2ec36c9507fbb665b38b .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-1aj4ev-3c0772d617fe2ec36c9507fbb665b38b av-styling- avia-align-center  avia-builder-el-2  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" class='wp-image-2741 avia-img-lazy-loading-not-2741 avia_image ' src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/INFINITT-RT-PACS-2-2.jpg\" alt='' title='INFINITT RT PACS-2'  height=\"415\" width=\"730\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/INFINITT-RT-PACS-2-2.jpg 730w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/INFINITT-RT-PACS-2-2-300x171.jpg 300w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/INFINITT-RT-PACS-2-2-705x401.jpg 705w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/div><\/div><\/div><\/div><div  class='flex_column av-12kcc7-f331206ce6b7f0df6ccb2e4344bbaf85 av_one_half  avia-builder-el-3  el_after_av_one_half  avia-builder-el-last  text-column flex_column_div  '     ><section  class='av_textblock_section av-lsd0v9tk-8564322e7efbf0c91bb4b366b7b0a4bb '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2122\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/04\/Infinitt_rt-pacs_logo.jpg\" alt=\"\" width=\"541\" height=\"40\" srcset=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/04\/Infinitt_rt-pacs_logo.jpg 541w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/04\/Infinitt_rt-pacs_logo-300x22.jpg 300w\" sizes=\"auto, (max-width: 541px) 100vw, 541px\" \/><\/p>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2g3zrb-0699ce71b6f125c5047e3c037010c8ed\">\n#top .av-special-heading.av-2g3zrb-0699ce71b6f125c5047e3c037010c8ed{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-2g3zrb-0699ce71b6f125c5047e3c037010c8ed .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-2g3zrb-0699ce71b6f125c5047e3c037010c8ed .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-2g3zrb-0699ce71b6f125c5047e3c037010c8ed av-special-heading-h1 custom-color-heading  avia-builder-el-5  el_after_av_textblock  el_before_av_textblock '><h1 class='av-special-heading-tag'  itemprop=\"headline\"  >Scentralizowany dost\u0119p do danych napromieniania dzi\u0119ki INFINITT RT PACS  <\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<section  class='av_textblock_section av-22h3ov-da4949e0b04164bc70170a40f9d787b1 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Oprogramowanie do <a href=\"https:\/\/infinitteurope.com\/pl\/radioterapia\/\">radioterapii<\/a> INFINITT optymalizuje zarz\u0105dzanie danymi w radioterapii (RT) i charakteryzuje si\u0119 przep\u0142ywem pracy skoncentrowanym na pacjencie.<br \/>\nDzi\u0119ki INFINITT RT PACS dane radioterapeutyczne z r\u00f3\u017cnych system\u00f3w planowania radioterapii mog\u0105 by\u0107 elastycznie archiwizowane, udost\u0119pniane i pobierane w czasie rzeczywistym.<\/p>\n<\/div><\/section>\n<div  class='avia-buttonrow-wrap av-lxov1osd-e44d38e6ffa8bb34a1514ceb2825eeb3 avia-buttonrow-left  avia-builder-el-7  el_after_av_textblock  avia-builder-el-last '>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lxov1nxq-f8df69fb4b53781f6e4a6ec6a14d38ad\">\n#top #wrap_all .avia-button.av-lxov1nxq-f8df69fb4b53781f6e4a6ec6a14d38ad{\nmargin-bottom:5px;\nmargin-right:5px;\n}\n<\/style>\n<a href='https:\/\/infinitteurope.com\/pl\/skontaktuj-sie-z-nami\/'  class='avia-button av-lxov1nxq-f8df69fb4b53781f6e4a6ec6a14d38ad avia-icon_select-no avia-size-small avia-color-theme-color'  ><span class='avia_iconbox_title' >Popro\u015b o prezentacj\u0119 produktu<\/span><\/a>\n<\/div><\/div>\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='av_section_2'  class='avia-section av-lrq6121a-2490886f07cb84515b5eecbb1be2f681 main_color avia-section-default avia-no-border-styling  avia-builder-el-8  el_after_av_section  el_before_av_section  img-text avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-5643'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-rraxr-88c15ef37c7cdde67e1a9cd60112b27a av_one_half  avia-builder-el-9  el_before_av_one_half  avia-builder-el-first  first flex_column_div  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mhpbj-0fa4f347ee694cdaba9840a09c54e88f\">\n#top .av-special-heading.av-mhpbj-0fa4f347ee694cdaba9840a09c54e88f{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-mhpbj-0fa4f347ee694cdaba9840a09c54e88f .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-mhpbj-0fa4f347ee694cdaba9840a09c54e88f .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-mhpbj-0fa4f347ee694cdaba9840a09c54e88f av-special-heading-h2 custom-color-heading  avia-builder-el-10  el_before_av_textblock  avia-builder-el-first '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >Optymalizacja zarz\u0105dzania danymi w radioterapii<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<section  class='av_textblock_section av-gnszr-7e78ac16aa00ae57f6bf236d67f67ca1 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>RT PACS to specjalne rozwi\u0105zanie dla radioterapii onkologicznej, kt\u00f3re umo\u017cliwia centralne zarz\u0105dzanie wszystkimi istotnymi klasami danych radioterapeutycznych.<\/p>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lxoa5je6-67ecd2f6d36c8751cb30fea351511ef4\">\n#top .avia-icon-list-container.av-lxoa5je6-67ecd2f6d36c8751cb30fea351511ef4 .iconlist_icon{\ncolor:#72246c;\n}\n<\/style>\n<div  class='avia-icon-list-container av-lxoa5je6-67ecd2f6d36c8751cb30fea351511ef4  avia-builder-el-12  el_after_av_textblock  avia-builder-el-last  icon-list-custom'><ul class='avia-icon-list avia_animate_when_almost_visible avia-icon-list-left av-iconlist-small av-lxoa5je6-67ecd2f6d36c8751cb30fea351511ef4 avia-iconlist-animate'>\n<li><div class='iconlist_icon av-76rw08-8a365d91efa85f121dcf76babe2a0cc5 avia-font-infinitt-icons'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue919' data-av_iconfont='infinitt-icons'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" >Przep\u0142yw pracy skoncentrowany na pacjencie<\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-6j4zag-abd8dd361d5736f08bf358c0a24aaa89 avia-font-infinitt-icons'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue919' data-av_iconfont='infinitt-icons'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" >Sta\u0142y dost\u0119p do wszystkich starszych danych z poprzednich system\u00f3w<\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-4aabc8-dcaba4844a0e24b4188395c72f8d8ade avia-font-infinitt-icons'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue919' data-av_iconfont='infinitt-icons'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" >Archiwizacja i zarz\u0105dzanie wszystkimi danymi planowania RT za po\u015brednictwem DICOM RT  <\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-1thxw8-8f9574ca352a3b97a0be10deb69b3a66 avia-font-infinitt-icons'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue919' data-av_iconfont='infinitt-icons'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" >Wizualizacja ca\u0142ego procesu RT  <\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-lxoa3eky-4ef25d0b09afb2235aa50a3095b3ed21 avia-font-infinitt-icons'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue919' data-av_iconfont='infinitt-icons'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" >Niezale\u017cna od producenta dystrybucja obraz\u00f3w i plan\u00f3w za po\u015brednictwem DICOM<\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-lxoa4vjs-5ad72b7d225d5ccf77030a4f82f0500b avia-font-infinitt-icons'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue919' data-av_iconfont='infinitt-icons'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><div class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" >Po\u0142\u0105czenie kontekstowe z EMR lub HIS<\/div><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<\/ul><\/div><\/div><div  class='flex_column av-l6w4v-a1348321512bcdd338556bff2577ec76 av_one_half  avia-builder-el-13  el_after_av_one_half  avia-builder-el-last  flex_column_div  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-bf1gv-3149796c943bead8c169bc786ac40f32\">\n.avia-image-container.av-bf1gv-3149796c943bead8c169bc786ac40f32 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-bf1gv-3149796c943bead8c169bc786ac40f32 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-bf1gv-3149796c943bead8c169bc786ac40f32 av-styling- avia-align-center  avia-builder-el-14  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" class='wp-image-2746 avia-img-lazy-loading-not-2746 avia_image ' src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/RT-PACS_585x435px-1.jpg\" alt='' title='RT-PACS_585x435px'  height=\"435\" width=\"585\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/RT-PACS_585x435px-1.jpg 585w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/RT-PACS_585x435px-1-300x223.jpg 300w\" sizes=\"(max-width: 585px) 100vw, 585px\" \/><\/div><\/div><\/div><\/div>\n\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-33m4en-d369e7962ca6fe80cd0fa91ab3cca1f9\">\n.avia-section.av-33m4en-d369e7962ca6fe80cd0fa91ab3cca1f9{\nbackground-color:#0f4074;\nbackground:linear-gradient( to bottom, #0f4074, #72246c );\nmargin-top:0px;\nmargin-bottom:0px;\n}\n<\/style>\n<div id='av_section_3'  class='avia-section av-33m4en-d369e7962ca6fe80cd0fa91ab3cca1f9 main_color avia-section-default avia-no-border-styling  avia-builder-el-15  el_after_av_section  el_before_av_section  background-gradient top avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-5643'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-2u31br-bb569d45182f47402817f1bc32a381c1 av_one_half  avia-builder-el-16  el_before_av_one_half  avia-builder-el-first  first flex_column_div  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2qjumf-a8512fb2c88e06c74617a90078bbe70f\">\n.avia-image-container.av-2qjumf-a8512fb2c88e06c74617a90078bbe70f img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-2qjumf-a8512fb2c88e06c74617a90078bbe70f .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-2qjumf-a8512fb2c88e06c74617a90078bbe70f av-styling- avia-align-center  avia-builder-el-17  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" class='wp-image-2191 avia-img-lazy-loading-not-2191 avia_image ' src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/04\/RT-PACS-Bildschirm-1.png\" alt='' title='Ekran RT-PACS'  height=\"580\" width=\"645\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/04\/RT-PACS-Bildschirm-1.png 645w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/04\/RT-PACS-Bildschirm-1-300x270.png 300w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/><\/div><\/div><\/div><\/div><div  class='flex_column av-2iq4nb-8ffb83397c7c77a00cd3045d332f3972 av_one_half  avia-builder-el-18  el_after_av_one_half  avia-builder-el-last  flex_column_div  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-g74on-f9f44d734f8c0f2df4272bdcc0e55b37\">\n#top .av-special-heading.av-g74on-f9f44d734f8c0f2df4272bdcc0e55b37{\npadding-bottom:10px;\ncolor:#ffffff;\n}\nbody .av-special-heading.av-g74on-f9f44d734f8c0f2df4272bdcc0e55b37 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-g74on-f9f44d734f8c0f2df4272bdcc0e55b37 .special-heading-inner-border{\nborder-color:#ffffff;\n}\n.av-special-heading.av-g74on-f9f44d734f8c0f2df4272bdcc0e55b37 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-g74on-f9f44d734f8c0f2df4272bdcc0e55b37 av-special-heading-h2 custom-color-heading  avia-builder-el-19  el_before_av_toggle_container  avia-builder-el-first '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >Dlaczego INFINITT RT PACS?<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lvfcl7rj-3b8f3143b159150d08fe1520c607d02d\">\n#top .togglecontainer.av-lvfcl7rj-3b8f3143b159150d08fe1520c607d02d p.toggler{\ncolor:#ffffff;\nborder-color:#ffffff;\n}\n#top .togglecontainer.av-lvfcl7rj-3b8f3143b159150d08fe1520c607d02d p.toggler .toggle_icon{\ncolor:#ffffff;\nborder-color:#ffffff;\n}\n#top .togglecontainer.av-lvfcl7rj-3b8f3143b159150d08fe1520c607d02d .toggle_wrap .toggle_content{\ncolor:#ffffff;\nborder-color:#ffffff;\n}\n<\/style>\n<div  class='togglecontainer av-lvfcl7rj-3b8f3143b159150d08fe1520c607d02d  avia-builder-el-20  el_after_av_heading  avia-builder-el-last '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/FAQPage\" >\n<section class='av_toggle_section av-akgw20-875ed63a706955937eec9d9abac7b6c0'  itemscope=\"itemscope\" itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Wszystko} \"  ><p data-fake-id='#toggle-id-1' class='toggler  activeTitle av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"name\"  role='tab' tabindex='0' aria-controls='toggle-id-1'>Doskona\u0142a obs\u0142uga i wsparcie ze strony specjalist\u00f3w RT PACS<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-1' class='toggle_wrap  active_tc' style='display:block;'  itemscope=\"itemscope\" itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\" ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p>Jako u\u017cytkownik otrzymasz obs\u0142ug\u0119 i wsparcie od naszych kompetentnych specjalist\u00f3w ds. aplikacji.<br \/>\nZesp\u00f3\u0142 produktowy sk\u0142ada si\u0119 z fizyk\u00f3w medycznych, ekspert\u00f3w fizyki medycznej, radiolog\u00f3w i MTR.<br \/>\nKa\u017cdy cz\u0142onek personelu posiada wiedz\u0119 specjalistyczn\u0105 i produktow\u0105, aby zaoferowa\u0107 najlepsz\u0105 mo\u017cliw\u0105 obs\u0142ug\u0119.<br \/>\nZ regu\u0142y przez ca\u0142y cykl \u017cycia urz\u0105dzenia, od szkolenia i instalacji po bie\u017c\u0105c\u0105 obs\u0142ug\u0119, przydzielana jest dedykowana osoba kontaktowa.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-lvfckwkx-09d62e245b71b7c783d70741b86eba97'  itemscope=\"itemscope\" itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Wszystko} \"  ><p data-fake-id='#toggle-id-2' class='toggler   av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"name\"  role='tab' tabindex='0' aria-controls='toggle-id-2'>Umo\u017cliwia wsp\u00f3\u0142prac\u0119 i dystrybucj\u0119 obraz\u00f3w<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-2' class='toggle_wrap  '   itemscope=\"itemscope\" itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\" ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p>Dzi\u0119ki INFINITT RT PACS dane radioterapeutyczne z r\u00f3\u017cnych system\u00f3w planowania radioterapii mog\u0105 by\u0107 wywo\u0142ywane w czasie rzeczywistym przez ca\u0142y odpowiedzialny personel w zale\u017cno\u015bci od pacjenta.<br \/>\nOdpowiednie dane mog\u0105 by\u0107 szybko i \u0142atwo wymieniane ze wsp\u00f3\u0142pracownikami.<br \/>\nU\u0142atwia to efektywn\u0105 wsp\u00f3\u0142prac\u0119 mi\u0119dzy onkologami, fizykami medycznymi, radioterapeutami i MTR.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-lvfcl6ow-84a52af6a147129e261093a617b9a98e'  itemscope=\"itemscope\" itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Wszystko} \"  ><p data-fake-id='#toggle-id-3' class='toggler   av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"name\"  role='tab' tabindex='0' aria-controls='toggle-id-3'>Optymalizuje przep\u0142yw pracy z wieloma formami terapii i urz\u0105dzeniami<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-3' class='toggle_wrap  '   itemscope=\"itemscope\" itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\" ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p>INFINITT RT PACS upraszcza archiwizacj\u0119 i zarz\u0105dzanie danymi radioterapeutycznymi, zw\u0142aszcza w przypadku pracy z wieloma metodami leczenia i urz\u0105dzeniami.<br \/>\nU\u017cytkownicy mog\u0105 uzyska\u0107 centralny dost\u0119p do wszystkich danych radioterapii z dowolnej stacji roboczej, niezale\u017cnie od systemu planowania, poniewa\u017c INFINITT RT PACS zapisuje je w znormalizowanym formacie danych.<br \/>\nUpraszcza to przep\u0142yw pracy, co skutkuje znaczn\u0105 oszcz\u0119dno\u015bci\u0105 czasu.<\/p>\n<\/div><\/div><\/div><\/section>\n<\/div><\/div>\n\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lrq5t0en-15b85ad9f48572ae87c9fd0ee341c2b0\">\n.avia-section.av-lrq5t0en-15b85ad9f48572ae87c9fd0ee341c2b0{\nbackground-color:#0f4074;\nbackground:linear-gradient( to top, #0f4074, #72246c );\nmargin-top:0px;\nmargin-bottom:0px;\n}\n<\/style>\n<div id='av_section_4'  class='avia-section av-lrq5t0en-15b85ad9f48572ae87c9fd0ee341c2b0 main_color avia-section-default avia-no-border-styling  avia-builder-el-21  el_after_av_section  el_before_av_section  background-gradient bottom product-show-slider avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-5643'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-19fpfj-761da75e237f1a5da6446b8d80012b9e av_one_third  avia-builder-el-22  el_before_av_two_third  avia-builder-el-first  first flex_column_div  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lrq5sdz2-f092db1ff4cecec72053d24183fbdb32\">\n#top .av-special-heading.av-lrq5sdz2-f092db1ff4cecec72053d24183fbdb32{\npadding-bottom:10px;\ncolor:#ffffff;\n}\nbody .av-special-heading.av-lrq5sdz2-f092db1ff4cecec72053d24183fbdb32 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-lrq5sdz2-f092db1ff4cecec72053d24183fbdb32 .special-heading-inner-border{\nborder-color:#ffffff;\n}\n.av-special-heading.av-lrq5sdz2-f092db1ff4cecec72053d24183fbdb32 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-lrq5sdz2-f092db1ff4cecec72053d24183fbdb32 av-special-heading-h2 custom-color-heading  avia-builder-el-23  el_before_av_textblock  avia-builder-el-first '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >Mo\u017cliwo\u015b\u0107 \u0142\u0105czenia<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lrq5siqc-73dc91c53d97bb577215d3e6f62320dd\">\n#top .av_textblock_section.av-lrq5siqc-73dc91c53d97bb577215d3e6f62320dd .avia_textblock{\ncolor:#ffffff;\n}\n<\/style>\n<section  class='av_textblock_section av-lrq5siqc-73dc91c53d97bb577215d3e6f62320dd '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><p>System PACS INFINITT RT mo\u017cna po\u0142\u0105czy\u0107 z nast\u0119puj\u0105cymi rozwi\u0105zaniami.<\/p>\n<\/div><\/section>\n<div  class='avia-button-wrap av-lrq5so2t-79df055efd6aa178835db3236f20fb0f-wrap avia-button-left  avia-builder-el-25  el_after_av_textblock  avia-builder-el-last '><a href='\/?page_id=54'  class='avia-button av-lrq5so2t-79df055efd6aa178835db3236f20fb0f avia-icon_select-yes-right-icon avia-size-small avia-position-left avia-color-light'  ><span class='avia_iconbox_title' >Wszystkie produkty<\/span><span class='avia_button_icon avia_button_icon_right' aria-hidden='true' data-av_icon='\ue907' data-av_iconfont='infinitt-icons'><\/span><\/a><\/div><\/div><div  class='flex_column av-pjjebc-58ee2585b8485661b1bfea4d8e2cdffc av_two_third  avia-builder-el-26  el_after_av_one_third  avia-builder-el-last  flex_column_div  '     ><div class='slider-div-wrapper' style='visibility:hidden'><div id='splide-contentslider-7204191' class='splides-slider   avia-builder-el-27  avia-builder-el-no-sibling  product-show ' data-splide='{\"focus\":0,\n\t            \t\t\t\t\t\"type\":\"loop\",\n\t            \t\t\t\t\t\"perMove\":1,\n\t            \t\t\t\t\t\"pagination\":false,\n\t            \t\t\t\t\t\"gap\":\"20px\",\n\t            \t\t\t\t\t\"perPage\":3,\n\t\t\t\t\t\t\t\t\t\"breakpoints\": {\"1024\": {\n                                            \"perPage\": \"2\"\n                                        },\"768\": {\n                                        \"perPage\": \"1\"\n                                        }} \n        }'><div class='splide__track'><ul class='splide__list'><li class='splide__slide slide-entry flex_column slide-width-1  only-image clickable' onclick=location.href='https:\/\/infinitteurope.com\/xelis-dental\/'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='background-contentslider' style='height:100%; background-size:cover;'><div class='product-img'><img src='https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/Xelis_Dental.png' class='slide-entry-img'><\/div><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" >Xelis Dental<\/h3><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2797 size-full\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/xelis-dental.jpg\" alt=\"\" width=\"174\" height=\"40\"><\/p>\n<\/div><div  class='avia-button-wrap avia-button-center  ' ><a href='https:\/\/infinitteurope.com\/xelis-dental\/'  class='avia-button avia-color-blue   '   ><span class='avia_iconbox_title' >Odkryj teraz<\/span><\/a><\/div><\/div><\/li><li class='splide__slide slide-entry flex_column slide-width-1  only-image clickable only-image clickable' onclick=location.href='https:\/\/infinitteurope.com\/infinitt-healthcare-platform\/'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='background-contentslider' style='height:100%; background-size:cover;'><div class='product-img'><img src='https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/VNA_freigestellt.png' class='slide-entry-img'><\/div><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" >Platforma opieki zdrowotnej INFINITT<\/h3><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1141 size-full\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/02\/Infinitt_healthcare-platform_logo.jpg\" alt=\"Platforma opieki zdrowotnej INFINITT\" width=\"880\" height=\"40\" srcset=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/02\/Infinitt_healthcare-platform_logo.jpg 880w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/02\/Infinitt_healthcare-platform_logo-300x14.jpg 300w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/02\/Infinitt_healthcare-platform_logo-768x35.jpg 768w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/02\/Infinitt_healthcare-platform_logo-705x32.jpg 705w\" sizes=\"auto, (max-width: 880px) 100vw, 880px\" \/><\/p>\n<\/div><div  class='avia-button-wrap avia-button-center  ' ><a href='https:\/\/infinitteurope.com\/infinitt-healthcare-platform\/'  class='avia-button avia-color-blue   '   ><span class='avia_iconbox_title' >Odkryj teraz<\/span><\/a><\/div><\/div><\/li><li class='splide__slide slide-entry flex_column slide-width-1  only-image clickable only-image clickable only-image clickable' onclick=location.href='https:\/\/infinitteurope.com\/infinitt-digital-pathology-solution\/'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='background-contentslider' style='height:100%; background-size:cover;'><div class='product-img'><img src='https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/INFINITT-Digital-Pathology.png' class='slide-entry-img'><\/div><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" >Rozwi\u0105zanie do patologii cyfrowej INFINITT<\/h3><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1133 size-full\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/02\/Infinitt_digital-pathology-solution_logo-3.jpg\" alt=\"Rozwi\u0105zanie do patologii cyfrowej INFINITT\" width=\"862\" height=\"40\" srcset=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/02\/Infinitt_digital-pathology-solution_logo-3.jpg 862w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/02\/Infinitt_digital-pathology-solution_logo-3-300x14.jpg 300w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/02\/Infinitt_digital-pathology-solution_logo-3-768x36.jpg 768w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/02\/Infinitt_digital-pathology-solution_logo-3-845x40.jpg 845w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/02\/Infinitt_digital-pathology-solution_logo-3-705x33.jpg 705w\" sizes=\"auto, (max-width: 862px) 100vw, 862px\" \/><\/p>\n<\/div><div  class='avia-button-wrap avia-button-center  ' ><a href='https:\/\/infinitteurope.com\/infinitt-digital-pathology-solution\/'  class='avia-button avia-color-blue   '   ><span class='avia_iconbox_title' >Odkryj teraz<\/span><\/a><\/div><\/div><\/li><li class='splide__slide slide-entry flex_column slide-width-1  only-image clickable only-image clickable only-image clickable only-image clickable' onclick=location.href='https:\/\/infinitteurope.com\/infinitt-dosem\/'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='background-contentslider' style='height:100%; background-size:cover;'><div class='product-img'><img src='https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/DoseM.png' class='slide-entry-img'><\/div><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" >INFINITT DoseM<\/h3><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3419 size-full\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Unbenannt-3-01.png\" alt=\"\" width=\"491\" height=\"39\" srcset=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Unbenannt-3-01.png 491w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Unbenannt-3-01-300x24.png 300w\" sizes=\"auto, (max-width: 491px) 100vw, 491px\" \/><\/p>\n<\/div><div  class='avia-button-wrap avia-button-center  ' ><a href='https:\/\/infinitteurope.com\/infinitt-dosem\/'  class='avia-button avia-color-blue   '   ><span class='avia_iconbox_title' >Odkryj teraz<\/span><\/a><\/div><\/div><\/li><li class='splide__slide slide-entry flex_column slide-width-1  only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable' onclick=location.href='https:\/\/infinitteurope.com\/infinitt-ai-platform\/'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='background-contentslider' style='height:100%; background-size:cover;'><div class='product-img'><img src='https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/INFINITT-AI-Website.png' class='slide-entry-img'><\/div><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" >Platforma AI INFINITT<\/h3><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2603 size-full\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Infinitt_ai-platform-logo.jpg\" alt=\"\" width=\"631\" height=\"40\" srcset=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Infinitt_ai-platform-logo.jpg 631w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Infinitt_ai-platform-logo-300x19.jpg 300w\" sizes=\"auto, (max-width: 631px) 100vw, 631px\" \/><\/p>\n<\/div><div  class='avia-button-wrap avia-button-center  ' ><a href='https:\/\/infinitteurope.com\/infinitt-ai-platform\/'  class='avia-button avia-color-blue   '   ><span class='avia_iconbox_title' >Odkryj teraz<\/span><\/a><\/div><\/div><\/li><li class='splide__slide slide-entry flex_column slide-width-1  only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable' onclick=location.href='https:\/\/infinitteurope.com\/infinitt-pacs\/'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='background-contentslider' style='height:100%; background-size:cover;'><div class='product-img'><img src='https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/INFINITT-PACS-7.0.png' class='slide-entry-img'><\/div><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" >INFINITT PACS 7.0<\/h3><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1388 size-full\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/03\/Infinitt_pacs-7.0_logo.jpg\" alt=\"INFINITT PACS 7.0\" width=\"527\" height=\"40\" srcset=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/03\/Infinitt_pacs-7.0_logo.jpg 527w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/03\/Infinitt_pacs-7.0_logo-300x23.jpg 300w\" sizes=\"auto, (max-width: 527px) 100vw, 527px\" \/><\/p>\n<\/div><div  class='avia-button-wrap avia-button-center  ' ><a href='https:\/\/infinitteurope.com\/infinitt-pacs\/'  class='avia-button avia-color-blue   '   ><span class='avia_iconbox_title' >Odkryj teraz<\/span><\/a><\/div><\/div><\/li><li class='splide__slide slide-entry flex_column slide-width-1  only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable' onclick=location.href='https:\/\/infinitteurope.com\/infinitt-fault-prevention-solution\/'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='background-contentslider' style='height:100%; background-size:cover;'><div class='product-img'><img src='https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/INFINITT-FPS-Enterprise.png' class='slide-entry-img'><\/div><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" >Rozwi\u0105zanie do zapobiegania awariom INFINITT<\/h3><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2730 size-full\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Infinitt_fault-prevention-solution_logo.jpg\" alt=\"\" width=\"986\" height=\"40\" srcset=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Infinitt_fault-prevention-solution_logo.jpg 986w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Infinitt_fault-prevention-solution_logo-300x12.jpg 300w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Infinitt_fault-prevention-solution_logo-768x31.jpg 768w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Infinitt_fault-prevention-solution_logo-705x29.jpg 705w\" sizes=\"auto, (max-width: 986px) 100vw, 986px\" \/><\/p>\n<\/div><div  class='avia-button-wrap avia-button-center  ' ><a href='https:\/\/infinitteurope.com\/infinitt-fault-prevention-solution\/'  class='avia-button avia-color-blue   '   ><span class='avia_iconbox_title' >Odkryj teraz<\/span><\/a><\/div><\/div><\/li><li class='splide__slide slide-entry flex_column slide-width-1  only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable' onclick=location.href='https:\/\/infinitteurope.com\/infinitt-ulite\/'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='background-contentslider' style='height:100%; background-size:cover;'><div class='product-img'><img src='https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/ULite-Website.png' class='slide-entry-img'><\/div><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" >ULite<\/h3><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3433 size-full\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/ULite_x40px.png\" alt=\"\" width=\"87\" height=\"40\"><\/p>\n<\/div><div  class='avia-button-wrap avia-button-center  ' ><a href='https:\/\/infinitteurope.com\/infinitt-ulite\/'  class='avia-button avia-color-blue   '   ><span class='avia_iconbox_title' >Odkryj teraz<\/span><\/a><\/div><\/div><\/li><li class='splide__slide slide-entry flex_column slide-width-1  only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable' onclick=location.href='https:\/\/infinitteurope.com\/infinitt-cardio-pacs\/'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='background-contentslider' style='height:100%; background-size:cover;'><div class='product-img'><img src='https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/INFINITT-Cardiology-PACS_IJP.png' class='slide-entry-img'><\/div><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" >INFINITT Cardio PACS<\/h3><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1709 size-full\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/03\/Infinitt_cardiology-pacs_logo.jpg\" alt=\"INFINITT Cardiology PACS\" width=\"630\" height=\"40\" srcset=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/03\/Infinitt_cardiology-pacs_logo.jpg 630w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/03\/Infinitt_cardiology-pacs_logo-300x19.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<\/div><div  class='avia-button-wrap avia-button-center  ' ><a href='https:\/\/infinitteurope.com\/infinitt-cardio-pacs\/'  class='avia-button avia-color-blue   '   ><span class='avia_iconbox_title' >Odkryj teraz<\/span><\/a><\/div><\/div><\/li><li class='splide__slide slide-entry flex_column slide-width-1  only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable' onclick=location.href='https:\/\/infinitteurope.com\/infinitt-mammo-pacs\/'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='background-contentslider' style='height:100%; background-size:cover;'><div class='product-img'><img src='https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/INFINITT-Mammo-PACS.png' class='slide-entry-img'><\/div><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" >INFINITT Mammo PACS<\/h3><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3361 size-full\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Unbenannt-1_Zeichenflaeche-1.png\" alt=\"\" width=\"677\" height=\"40\" srcset=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Unbenannt-1_Zeichenflaeche-1.png 677w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Unbenannt-1_Zeichenflaeche-1-300x18.png 300w\" sizes=\"auto, (max-width: 677px) 100vw, 677px\" \/><\/p>\n<\/div><div  class='avia-button-wrap avia-button-center  ' ><a href='https:\/\/infinitteurope.com\/infinitt-mammo-pacs\/'  class='avia-button avia-color-blue   '   ><span class='avia_iconbox_title' >Odkryj teraz<\/span><\/a><\/div><\/div><\/li><li class='splide__slide slide-entry flex_column slide-width-1  only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable' onclick=location.href='https:\/\/infinitteurope.com\/infinitt-dental-pacs\/'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='background-contentslider' style='height:100%; background-size:cover;'><div class='product-img'><img src='https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/Dental-PACS.png' class='slide-entry-img'><\/div><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" >INFINITT Dental PACS<\/h3><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3414 size-full\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Unbenannt-4-01.png\" alt=\"\" width=\"639\" height=\"39\" srcset=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Unbenannt-4-01.png 639w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Unbenannt-4-01-300x18.png 300w\" sizes=\"auto, (max-width: 639px) 100vw, 639px\" \/><\/p>\n<\/div><div  class='avia-button-wrap avia-button-center  ' ><a href='https:\/\/infinitteurope.com\/infinitt-dental-pacs\/'  class='avia-button avia-color-blue   '   ><span class='avia_iconbox_title' >Odkryj teraz<\/span><\/a><\/div><\/div><\/li><li class='splide__slide slide-entry flex_column slide-width-1  only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable' onclick=location.href='https:\/\/infinitteurope.com\/infinitt-ophthalmologie-pacs\/'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='background-contentslider' style='height:100%; background-size:cover;'><div class='product-img'><img src='https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/Ophthalmology-PACS-website.png' class='slide-entry-img'><\/div><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" >INFINITT Ophthalmology PACS<\/h3><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3374 size-full\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Unbenannt-1-03.png\" alt=\"\" width=\"610\" height=\"40\" srcset=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Unbenannt-1-03.png 610w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/Unbenannt-1-03-300x20.png 300w\" sizes=\"auto, (max-width: 610px) 100vw, 610px\" \/><\/p>\n<\/div><div  class='avia-button-wrap avia-button-center  ' ><a href='https:\/\/infinitteurope.com\/infinitt-ophthalmologie-pacs\/'  class='avia-button avia-color-blue   '   ><span class='avia_iconbox_title' >Odkryj teraz<\/span><\/a><\/div><\/div><\/li><li class='splide__slide slide-entry flex_column slide-width-1  only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable' onclick=location.href='https:\/\/infinitteurope.com\/infinitt-vet-pacs\/'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='background-contentslider' style='height:100%; background-size:cover;'><div class='product-img'><img src='https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/Vet-PACS-website.png' class='slide-entry-img'><\/div><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" >INFINITT Vet PACS<\/h3><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1111 size-full\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/02\/Infinitt_vet-pacs_logo.jpg\" alt=\"Infinitt Vet Pacs\" width=\"567\" height=\"40\" srcset=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/02\/Infinitt_vet-pacs_logo.jpg 567w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/02\/Infinitt_vet-pacs_logo-300x21.jpg 300w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/p>\n<\/div><div  class='avia-button-wrap avia-button-center  ' ><a href='https:\/\/infinitteurope.com\/infinitt-vet-pacs\/'  class='avia-button avia-color-blue   '   ><span class='avia_iconbox_title' >Odkryj teraz<\/span><\/a><\/div><\/div><\/li><li class='splide__slide slide-entry flex_column slide-width-1  only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable only-image clickable' onclick=location.href='https:\/\/infinitteurope.com\/xelis\/'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='background-contentslider' style='height:100%; background-size:cover;'><div class='product-img'><img src='https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/Xelis3-D.png' class='slide-entry-img'><\/div><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" >Xelis<\/h3><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2803 size-full\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/05\/xelis.jpg\" alt=\"\" width=\"93\" height=\"40\"><\/p>\n<\/div><div  class='avia-button-wrap avia-button-center  ' ><a href='https:\/\/infinitteurope.com\/xelis\/'  class='avia-button avia-color-blue   '   ><span class='avia_iconbox_title' >Odkryj teraz<\/span><\/a><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><script type=\"text\/javascript\">\n\t\t\t\t\t\t\t\tjQuery(window).on(\"load\",function() {\n\t\t\t\t\t\t\t\t\tvar splide7204191 = new Splide( \"#splide-contentslider-7204191\" );\n\n\t\t\t\t\t\t\t\t\tsplide7204191.on( \"mounted\", function () {\n\t\t\t\t\t\t\t\t\t\tjQuery(\"#splide-contentslider-7204191\").parent()\n\t\t\t\t\t\t\t\t\t\t\t\t.css(\"visibility\",\"visible\")\n\t\t\t\t\t\t\t\t\t\t\t\t.hide()\n\t\t\t\t\t\t\t\t\t\t\t\t.slideDown(1300,\"swing\")\n\t\t\t\t\t\t\t\t\t\t\t\t.css(\"opacity\",0)\n\t\t\t\t\t\t\t\t\t\t\t\t.animate(\n\t\t\t\t\t\t\t\t\t\t\t\t\t{ opacity:1 },\n    \t\t\t\t\t\t\t\t\t\t\t{ queue: false, duration: 1300 }\n  \t\t\t\t\t\t\t\t\t\t\t);\n\t\t\t\t\t\t\t\t\t} );\n\n\t\t\t\t\t\t\t\t\tsplide7204191.mount();\n\n                                    \n\n\n\n\t\t\t\t\t\t\t\t});\n\t\t\t\t\t\t<\/script><\/div>\n\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_5'  class='avia-section av-hoh7j-7dbc15e7f1cd55d0892e8e41cf65c338 main_color avia-section-default avia-no-border-styling  avia-builder-el-28  el_after_av_section  el_before_av_layout_row  before-features-grid avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-5643'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-b0g07-6f01c3e1e5801c41ecc35610769a6e9c av_two_fifth  avia-builder-el-29  avia-builder-el-no-sibling  first flex_column_div  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lrqblfcq-d7bec7228c5c79a3810113c5c6892701\">\n#top .av-special-heading.av-lrqblfcq-d7bec7228c5c79a3810113c5c6892701{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-lrqblfcq-d7bec7228c5c79a3810113c5c6892701 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-lrqblfcq-d7bec7228c5c79a3810113c5c6892701 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-lrqblfcq-d7bec7228c5c79a3810113c5c6892701 av-special-heading-h2 blockquote modern-quote modern-centered  avia-builder-el-30  el_before_av_textblock  avia-builder-el-first '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >Cechy<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lrqbl8xf-ce307aa1ebe5f1de3e23231e7db26bf0\">\n#top .av_textblock_section.av-lrqbl8xf-ce307aa1ebe5f1de3e23231e7db26bf0 .avia_textblock{\ntext-align:center;\n}\n<\/style>\n<section  class='av_textblock_section av-lrqbl8xf-ce307aa1ebe5f1de3e23231e7db26bf0 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>INFINITT RT PACS oferuje szeroki zakres intuicyjnych funkcji, kt\u00f3re s\u0105 stale rozwijane.<\/p>\n<\/div><\/section><\/div>\n\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av-layout-grid-1'  class='av-layout-grid-container av-lr7y1uj4-5be964f70a52d83f8ac2fbc433573489 entry-content-wrapper main_color av-flex-cells  avia-builder-el-32  el_after_av_section  el_before_av_section  features-grid grid-row-not-first  container_wrap fullsize'  >\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lr7xvy7u-fe915ecff9fbd097bc5811b4dda07059\">\n.flex_cell.av-lr7xvy7u-fe915ecff9fbd097bc5811b4dda07059{\nvertical-align:top;\n}\n<\/style>\n<div class='flex_cell av-lr7xvy7u-fe915ecff9fbd097bc5811b4dda07059 av-gridrow-cell av_one_third no_margin  avia-builder-el-33  el_before_av_cell_one_third  avia-builder-el-first '  ><div class='flex_cell_inner'><p><div  class='flex_column av-3i95ef-6b188ac3b42726cb16bc764407eed5f6 av_one_full  avia-builder-el-34  el_before_av_one_full  avia-builder-el-first  first flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ls0d6l7i-e7417e009b865bb8225ed297d9d033ac\">\n.av_font_icon.av-ls0d6l7i-e7417e009b865bb8225ed297d9d033ac .av-icon-char{\nfont-size:32px;\nline-height:32px;\nwidth:32px;\n}\n<\/style>\n<span  class='av_font_icon av-ls0d6l7i-e7417e009b865bb8225ed297d9d033ac avia_animate_when_visible av-icon-style-border avia-icon-pos-left av-no-color avia-icon-animate'><span class='av-icon-char' aria-hidden='true' data-av_icon='\ue91f' data-av_iconfont='infinitt-icons' ><\/span><\/span><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7j57b-6cc712116028f76136d50b3eb732df69\">\n#top .av-special-heading.av-7j57b-6cc712116028f76136d50b3eb732df69{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-7j57b-6cc712116028f76136d50b3eb732df69 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-7j57b-6cc712116028f76136d50b3eb732df69 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-7j57b-6cc712116028f76136d50b3eb732df69 av-special-heading-h5  avia-builder-el-36  el_after_av_font_icon  el_before_av_textblock '><h5 class='av-special-heading-tag'  itemprop=\"headline\"  >Obs\u0142uga wszystkich danych planowania<\/h5><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-kqkxz-1400e78255d24bc1f146e341bd760868 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>CT \/ ROI, rozk\u0142ad dawki, obrazy DRR \/ obrazy portali, wykresy DVH, informacje o promieniowaniu.<\/p>\n<\/div><\/section><\/p><\/div><div  class='flex_column av-20qsmv-f04d59ea34c2ea53f4c7945558c98068 av_one_full  avia-builder-el-38  el_after_av_one_full  avia-builder-el-last  first flex_column_div  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ls0cxz7q-8504e36a128c7033e636c626d25e5bcf\">\n.av_font_icon.av-ls0cxz7q-8504e36a128c7033e636c626d25e5bcf .av-icon-char{\nfont-size:32px;\nline-height:32px;\nwidth:32px;\n}\n<\/style>\n<span  class='av_font_icon av-ls0cxz7q-8504e36a128c7033e636c626d25e5bcf avia_animate_when_visible av-icon-style-border avia-icon-pos-left av-no-color avia-icon-animate'><span class='av-icon-char' aria-hidden='true' data-av_icon='\ue91c' data-av_iconfont='infinitt-icons' ><\/span><\/span><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lr7ygvpa-8bf6ac431e61add00c30c0d229ef149c\">\n#top .av-special-heading.av-lr7ygvpa-8bf6ac431e61add00c30c0d229ef149c{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-lr7ygvpa-8bf6ac431e61add00c30c0d229ef149c .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-lr7ygvpa-8bf6ac431e61add00c30c0d229ef149c .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-lr7ygvpa-8bf6ac431e61add00c30c0d229ef149c av-special-heading-h5  avia-builder-el-40  el_after_av_font_icon  el_before_av_textblock '><h5 class='av-special-heading-tag'  itemprop=\"headline\"  >Reprezentacja 3D<\/h5><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-bp44f-a41dfbffd72aecefab14b84c339b3252 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Tryb osiowy, strza\u0142kowy, czo\u0142owy i VR.<\/p>\n<\/div><\/section><\/p><\/div><\/p>\n<\/div><\/div><div class='flex_cell av-272jpj-421d144b22207caeb2afd6d120923c68 av-gridrow-cell av_one_third no_margin  avia-builder-el-42  el_after_av_cell_one_third  el_before_av_cell_one_third '  ><div class='flex_cell_inner'><p><div  class='flex_column av-2v6k5z-7deda4eb2132738fdc32dd6c482de23f av_one_full  avia-builder-el-43  el_before_av_one_full  avia-builder-el-first  first flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ls0d73m0-4f1e86cf6fb95bf14f44be52d2e59708\">\n.av_font_icon.av-ls0d73m0-4f1e86cf6fb95bf14f44be52d2e59708 .av-icon-char{\nfont-size:32px;\nline-height:32px;\nwidth:32px;\n}\n<\/style>\n<span  class='av_font_icon av-ls0d73m0-4f1e86cf6fb95bf14f44be52d2e59708 avia_animate_when_visible av-icon-style-border avia-icon-pos-left av-no-color avia-icon-animate'><span class='av-icon-char' aria-hidden='true' data-av_icon='\ue90d' data-av_iconfont='infinitt-icons' ><\/span><\/span><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lr7ygpit-8d0a6811f208af13e0255c902f8d5d2d\">\n#top .av-special-heading.av-lr7ygpit-8d0a6811f208af13e0255c902f8d5d2d{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-lr7ygpit-8d0a6811f208af13e0255c902f8d5d2d .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-lr7ygpit-8d0a6811f208af13e0255c902f8d5d2d .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-lr7ygpit-8d0a6811f208af13e0255c902f8d5d2d av-special-heading-h5  avia-builder-el-45  el_after_av_font_icon  el_before_av_textblock '><h5 class='av-special-heading-tag'  itemprop=\"headline\"  >Sumowanie i por\u00f3wnywanie plan\u00f3w<\/h5><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-hfy3z-e0e01cacb425767070258d711bf09d22 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Podsumowanie dawki i por\u00f3wnanie r\u00f3\u017cnych plan\u00f3w oceny jako\u015bci.<\/p>\n<\/div><\/section><\/p><\/div><div  class='flex_column av-3wl4e3-1bb73201f6f0ac9096664cc7c428a7c2 av_one_full  avia-builder-el-47  el_after_av_one_full  avia-builder-el-last  first flex_column_div  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ltqzvg67-a91e76721f3ebe7ee10d3bb74da53750\">\n.av_font_icon.av-ltqzvg67-a91e76721f3ebe7ee10d3bb74da53750 .av-icon-char{\nfont-size:32px;\nline-height:32px;\nwidth:32px;\n}\n<\/style>\n<span  class='av_font_icon av-ltqzvg67-a91e76721f3ebe7ee10d3bb74da53750 avia_animate_when_visible av-icon-style-border avia-icon-pos-left av-no-color avia-icon-animate'><span class='av-icon-char' aria-hidden='true' data-av_icon='\ue923' data-av_iconfont='infinitt-icons' ><\/span><\/span><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ltqzteba-c4488e5f92eafa72ce1a82f8b05c785b\">\n#top .av-special-heading.av-ltqzteba-c4488e5f92eafa72ce1a82f8b05c785b{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-ltqzteba-c4488e5f92eafa72ce1a82f8b05c785b .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-ltqzteba-c4488e5f92eafa72ce1a82f8b05c785b .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-ltqzteba-c4488e5f92eafa72ce1a82f8b05c785b av-special-heading-h5  avia-builder-el-49  el_after_av_font_icon  el_before_av_textblock '><h5 class='av-special-heading-tag'  itemprop=\"headline\"  >Niezale\u017cny od producenta<\/h5><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-ltqzsry9-ec654b34123e4c06a1d6be57add648c1 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Oprogramowanie mo\u017ce by\u0107 u\u017cywane niezale\u017cnie od pod\u0142\u0105czonego oprogramowania i producent\u00f3w urz\u0105dze\u0144.<\/p>\n<\/div><\/section><\/p><\/div><\/p>\n<\/div><\/div><div class='flex_cell av-5fosqw-2f1333ec85d5fdf9ac91bdf7ff3e9554 av-gridrow-cell av_one_third no_margin  avia-builder-el-51  el_after_av_cell_one_third  avia-builder-el-last '  ><div class='flex_cell_inner'><div  class='flex_column av-4xgxmw-1d935bdb02d91d0565624e53993b366d av_one_full  avia-builder-el-52  avia-builder-el-no-sibling  first flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lvgnop75-7cc506a7a682dcef72d7d8a2eb0d54ef\">\n.av_font_icon.av-lvgnop75-7cc506a7a682dcef72d7d8a2eb0d54ef .av-icon-char{\nfont-size:32px;\nline-height:32px;\nwidth:32px;\n}\n<\/style>\n<span  class='av_font_icon av-lvgnop75-7cc506a7a682dcef72d7d8a2eb0d54ef avia_animate_when_visible av-icon-style-border avia-icon-pos-left av-no-color avia-icon-animate'><span class='av-icon-char' aria-hidden='true' data-av_icon='\ue90a' data-av_iconfont='infinitt-icons' ><\/span><\/span><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lvgnoem6-e30e01bc36556b48a0fa27af06423fb8\">\n#top .av-special-heading.av-lvgnoem6-e30e01bc36556b48a0fa27af06423fb8{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-lvgnoem6-e30e01bc36556b48a0fa27af06423fb8 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-lvgnoem6-e30e01bc36556b48a0fa27af06423fb8 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-lvgnoem6-e30e01bc36556b48a0fa27af06423fb8 av-special-heading-h5  avia-builder-el-54  el_after_av_font_icon  el_before_av_iconlist '><h5 class='av-special-heading-tag'  itemprop=\"headline\"  >Dalsze funkcje<\/h5><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<div  class='avia-icon-list-container av-lxoa9qpj-0048701afa81d4e4c67ebb8cedfbef06  avia-builder-el-55  el_after_av_heading  avia-builder-el-last '><ul class='avia-icon-list avia_animate_when_almost_visible avia-icon-list-left av-iconlist-small av-lxoa9qpj-0048701afa81d4e4c67ebb8cedfbef06 avia-iconlist-animate'>\n<li><div class='iconlist_icon av-lxoa6r0u-f81754216e4691fd78ba43258f99d264 avia-font-infinitt-icons'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue919' data-av_iconfont='infinitt-icons'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><p class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" >Elastyczny dost\u0119p z dowolnej lokalizacji<\/p><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-eyvs8-14268e240bd7ce19074ee5860e3e6b30 avia-font-infinitt-icons'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue919' data-av_iconfont='infinitt-icons'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><p class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" >Przekazywanie danych<\/p><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-a7788-482ef6be84ba2663a1e01ed8ecdd2289 avia-font-infinitt-icons'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue919' data-av_iconfont='infinitt-icons'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><p class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" >Integracja z EMR i HIS<\/p><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-lxoa8kkd-a39e8c5ed3da902765a96b03a3dd1992 avia-font-infinitt-icons'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue919' data-av_iconfont='infinitt-icons'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><p class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" >System obs\u0142uguj\u0105cy wielu klient\u00f3w<\/p><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-lxoa9phx-a94a30e75fb0b537c6fe03ecf4f09087 avia-font-infinitt-icons'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue919' data-av_iconfont='infinitt-icons'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><p class='av_iconlist_title iconlist_title_small  '  itemprop=\"headline\" >Efektywne wykorzystanie dost\u0119pnej przestrzeni dyskowej<\/p><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<\/ul><\/div><\/p><\/div>\n<\/div><\/div>\n<\/div>\n\n<div id='av_section_6'  class='avia-section av-6oabnz-570c165219178cd3f00777032e220929 main_color avia-section-default avia-no-border-styling  avia-builder-el-56  el_after_av_layout_row  el_before_av_section  schwung-section avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-5643'><div class='entry-content-wrapper clearfix'>\n<div class='flex_column_table av-6h3atj-7b309365080a38dd199dc9624a944e31 sc-av_one_half av-equal-height-column-flextable'><div  class='flex_column av-6h3atj-7b309365080a38dd199dc9624a944e31 av_one_half  avia-builder-el-57  el_before_av_one_half  avia-builder-el-first  text-column first flex_column_table_cell av-equal-height-column av-align-bottom  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6f6mlj-312cefad10efd3bf4095bc276639a396\">\n#top .av-special-heading.av-6f6mlj-312cefad10efd3bf4095bc276639a396{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-6f6mlj-312cefad10efd3bf4095bc276639a396 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-6f6mlj-312cefad10efd3bf4095bc276639a396 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-6f6mlj-312cefad10efd3bf4095bc276639a396 av-special-heading-h2  avia-builder-el-58  el_before_av_textblock  avia-builder-el-first '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >Wi\u0119cej informacji na temat INFINITT RT PACS?<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<section  class='av_textblock_section av-67vj5b-c44cd1bad2317f92f28346e484d8a4d3 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Nasi do\u015bwiadczeni specjali\u015bci znajd\u0105 dla Ciebie odpowiednie rozwi\u0105zania.<\/p>\n<\/div><\/section>\n<div  class='avia-buttonrow-wrap av-lxov1wcu-e63b92330d16410b8e0966c1e431af9c avia-buttonrow-left  avia-builder-el-60  el_after_av_textblock  avia-builder-el-last '>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1utb54-6dc3f9a82f900d4d903aa2cfa681a14e\">\n#top #wrap_all .avia-button.av-1utb54-6dc3f9a82f900d4d903aa2cfa681a14e{\nmargin-bottom:5px;\nmargin-right:5px;\n}\n<\/style>\n<a href='https:\/\/infinitteurope.com\/pl\/skontaktuj-sie-z-nami\/'  class='avia-button av-1utb54-6dc3f9a82f900d4d903aa2cfa681a14e avia-icon_select-no avia-size-small avia-color-theme-color'  ><span class='avia_iconbox_title' >Skontaktuj si\u0119 z nami<\/span><\/a>\n<\/div><\/div><div class='av-flex-placeholder'><\/div><div  class='flex_column av-jwvhz-7782cfcf8f5b6d9bd286f72dc36113c9 av_one_half  avia-builder-el-61  el_after_av_one_half  avia-builder-el-last  img-column flex_column_table_cell av-equal-height-column av-align-bottom  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5c5siv-cdd8fea66aec851ab3e854e7cfa523d8\">\n.avia-image-container.av-5c5siv-cdd8fea66aec851ab3e854e7cfa523d8 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-5c5siv-cdd8fea66aec851ab3e854e7cfa523d8 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-5c5siv-cdd8fea66aec851ab3e854e7cfa523d8 av-styling- avia-align-right  avia-builder-el-62  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" class='wp-image-591 avia-img-lazy-loading-not-591 avia_image ' src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/01\/Gruppe-1420.jpg\" alt='' title='Gruppe 1420'  height=\"507\" width=\"748\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/01\/Gruppe-1420.jpg 748w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/01\/Gruppe-1420-300x203.jpg 300w, https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/01\/Gruppe-1420-705x478.jpg 705w\" sizes=\"(max-width: 748px) 100vw, 748px\" \/><\/div><\/div><\/div><\/div><\/div><!--close column table wrapper. Autoclose: 1 -->\n\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_7'  class='avia-section av-588s4v-31040c7791b7e45da60ae659070ca47f main_color avia-section-default avia-no-border-styling  avia-builder-el-63  el_after_av_section  el_before_av_postcontent  customer-quotes-full-sec avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-5643'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-51etyv-6b7cf717abdc6d4841bf639aa540e5bf av_one_full  avia-builder-el-64  el_before_av_one_full  avia-builder-el-first  first flex_column_div  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4vhszj-7f0fead9d8867ed64a8073a7f68d8142\">\n#top .av-special-heading.av-4vhszj-7f0fead9d8867ed64a8073a7f68d8142{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-4vhszj-7f0fead9d8867ed64a8073a7f68d8142 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-4vhszj-7f0fead9d8867ed64a8073a7f68d8142 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-4vhszj-7f0fead9d8867ed64a8073a7f68d8142 av-special-heading-h2 blockquote modern-quote modern-centered  avia-builder-el-65  avia-builder-el-no-sibling '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >Wieloletni klienci s\u0105 przekonani<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><\/div><div  class='flex_column av-4p1f8v-307fc1e166eec04f0d8ffc19218f6e5f av_one_full  avia-builder-el-66  el_after_av_one_full  avia-builder-el-last  customer-quotes-full-column first flex_column_div  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4hvx6n-1952114566dc4bfb1b2c7c7b72e01262\">\n#top .hr.av-4hvx6n-1952114566dc4bfb1b2c7c7b72e01262{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-4hvx6n-1952114566dc4bfb1b2c7c7b72e01262 .hr-inner{\nwidth:100%;\nmax-width:45%;\n}\n<\/style>\n<div  class='hr av-4hvx6n-1952114566dc4bfb1b2c7c7b72e01262 hr-custom  avia-builder-el-67  el_before_econsor_postslider  avia-builder-el-first  hr-center hr-icon-yes'><span class='hr-inner inner-border-av-border-thin'><span class=\"hr-inner-style\"><\/span><\/span><span class='av-seperator-icon' aria-hidden='true' data-av_icon='\ue91d' data-av_iconfont='infinitt-icons'><\/span><span class='hr-inner inner-border-av-border-thin'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div id='splide-postslider-16904629' class='splides-slider splide-post-slider  avia-builder-el-68  el_after_av_hr  el_before_av_hr  kundenstimme-slider' data-splide='{\"focus\":0, \n\t            \t\t\t\t\t\"type\":\"loop\",\n\t            \t\t\t\t\t\"arrows\":true,\n\t            \t\t\t\t\t\"perMove\":1,\n\t            \t\t\t\t\t\"pagination\":false,\n\t\t            \t\t\t\t\"gap\":\"20px\",\n\t            \t\t\t\t\t\"perPage\":1,\n\t\t\t\t\t\t\t\t\t\t\"breakpoints\": {} \n        }'><div class='splide__track'><ul class='splide__list'><li class='splide__slide slide-entry flex_column  slider-category-aktualnosci real-thumbnail post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/infinitteurope.com\/pl\/news\/najczesciej-zadawane-pytania-dotyczace-patologii-cyfrowej-skanery-procesy-robocze-sztuczna-inteligencja-i-archiwizacja\/' data-rel='slide-1' class='slide-image' title='Najcz\u0119\u015bciej zadawane pytania dotycz\u0105ce patologii cyfrowej: skanery, procesy robocze, sztuczna inteligencja i archiwizacja'><img decoding=\"async\" width=\"495\" height=\"380\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2026\/08\/FAQ-DPS-495x380.png\" class=\"wp-image-10237 avia-img-lazy-loading-not-10237 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class='slide-content'><header class=\"entry-content-header\"><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/infinitteurope.com\/pl\/news\/najczesciej-zadawane-pytania-dotyczace-patologii-cyfrowej-skanery-procesy-robocze-sztuczna-inteligencja-i-archiwizacja\/' title='Najcz\u0119\u015bciej zadawane pytania dotycz\u0105ce patologii cyfrowej: skanery, procesy robocze, sztuczna inteligencja i archiwizacja'>Najcz\u0119\u015bciej zadawane pytania dotycz\u0105ce patologii cyfrowej: skanery, procesy robocze, sztuczna inteligencja i archiwizacja<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-meta'><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2026-08-27T10:02:04+02:00\" >2026-08-27<\/time><\/div><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" >Wprowadzenie patologii cyfrowej rodzi wiele pyta\u0144. Odpowiadamy na najwa\u017cniejsze z nich i pokazujemy, w jaki spos\u00f3b rozwi\u0105zanie INFINITT Digital Pathology Solution (DPS) mo\u017ce wspiera\u0107 laboratoria w procesie cyfryzacji. <\/div><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/infinitteurope.com\/wp-content\/uploads\/2026\/08\/FAQ-DPS.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>380<\/span>\n\t\t\t\t\t\t<span itemprop='width'>570<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>Gabriela Schuette<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>\/wp-content\/uploads\/2023\/11\/ieu_logo_blue.svg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>Gabriela Schuette<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2024-04-25T16:01:40+02:00\" >2026-08-27 10:02:04<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2026-08-31 09:56:14<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Najcz\u0119\u015bciej zadawane pytania dotycz\u0105ce patologii cyfrowej: skanery, procesy robocze, sztuczna inteligencja i archiwizacja<\/span><\/span><\/span><\/li><li class='splide__slide slide-entry flex_column  slider-category-radiologia fake-thumbnail post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/infinitteurope.com\/pl\/kundenstimmen\/szpital-sw-jerzego\/' data-rel='slide-1' class='slide-image' title='Szpital \u015bw. Jerzego'><span class=' fallback-post-type-icon' aria-hidden='true' data-av_icon='\ue836' data-av_iconfont='entypo-fontello'><\/span><span class='slider-fallback-image'><img decoding=\"async\" width=\"495\" height=\"380\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2026\/08\/FAQ-DPS-495x380.png\" class=\"wp-image-10237 avia-img-lazy-loading-not-10237 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/span><\/a><div class='slide-content'><header class=\"entry-content-header\"><div class='slide-entry-zitat'><p> INFINITT jest niezawodnym i wiod\u0105cym globalnym dostawc\u0105 o wysokim poziomie wiedzy specjalistycznej w zakresie produkt\u00f3w. Jest to jeden z powod\u00f3w, dla kt\u00f3rych szpital St. Georg jest klientem INFINITT od ponad 14 lat. Korzystamy ju\u017c z INFINITT PACS i INFINITT DoseM, a obecnie wdra\u017camy RT PACS do radioterapii. <\/p><\/div><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-name'><p> Prof. Dr. med. Arnd-Oliver Sch\u00e4fer <\/p><\/div><div class='slide-entry-position'><p> G\u0142\u00f3wny lekarz, Klinika Radiologii i Medycyny Nuklearnej, Klinikum St. Georg, Lipsk <\/p><\/div><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>\/wp-content\/uploads\/2023\/11\/ieu_logo_blue.svg<\/span>\n\t\t\t\t\t\t<span itemprop='height'>0<\/span>\n\t\t\t\t\t\t<span itemprop='width'>0<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>econsor<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>\/wp-content\/uploads\/2023\/11\/ieu_logo_blue.svg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>econsor<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2024-04-25T16:01:40+02:00\" >2024-02-07 12:04:56<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-07-29 10:18:20<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Szpital \u015bw. Jerzego<\/span><\/span><\/span><\/li><li class='splide__slide slide-entry flex_column  slider-category-pacs-pl fake-thumbnail post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/infinitteurope.com\/pl\/kundenstimmen\/radmedics\/' data-rel='slide-1' class='slide-image' title='RadMedics'><span class=' fallback-post-type-icon' aria-hidden='true' data-av_icon='\ue836' data-av_iconfont='entypo-fontello'><\/span><span class='slider-fallback-image'><img decoding=\"async\" width=\"495\" height=\"380\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2026\/08\/FAQ-DPS-495x380.png\" class=\"wp-image-10237 avia-img-lazy-loading-not-10237 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/span><\/a><div class='slide-content'><header class=\"entry-content-header\"><div class='slide-entry-zitat'><p> U\u017cywamy INFINITT PACS zar\u00f3wno do naszych us\u0142ug radiologicznych za po\u015brednictwem teleradiologie.net, jak i w naszych 13 lokalizacjach. To, co szczeg\u00f3lnie podoba nam si\u0119 w INFINITT PACS, to zakres funkcji, elastyczne opcje konfiguracji i obs\u0142uga zorientowana na klienta. <\/p><\/div><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-name'><p> Dr. med. Jan Mari\u00df <\/p><\/div><div class='slide-entry-position'><p> Dyrektor medyczny ds. radiologii w p\u00f3\u0142nocnej i \u015brodkowej Hesji; Teleradiologie.net <\/p><\/div><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>\/wp-content\/uploads\/2023\/11\/ieu_logo_blue.svg<\/span>\n\t\t\t\t\t\t<span itemprop='height'>0<\/span>\n\t\t\t\t\t\t<span itemprop='width'>0<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>econsor<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>\/wp-content\/uploads\/2023\/11\/ieu_logo_blue.svg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>econsor<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2024-04-25T16:01:40+02:00\" >2024-02-07 11:54:11<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-07-29 11:40:31<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>RadMedics<\/span><\/span><\/span><\/li><li class='splide__slide slide-entry flex_column  slider-category-radiologia fake-thumbnail post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/infinitteurope.com\/pl\/kundenstimmen\/hug\/' data-rel='slide-1' class='slide-image' title='HUG'><span class=' fallback-post-type-icon' aria-hidden='true' data-av_icon='\ue836' data-av_iconfont='entypo-fontello'><\/span><span class='slider-fallback-image'><img decoding=\"async\" width=\"495\" height=\"380\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2026\/08\/FAQ-DPS-495x380.png\" class=\"wp-image-10237 avia-img-lazy-loading-not-10237 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/span><\/a><div class='slide-content'><header class=\"entry-content-header\"><div class='slide-entry-zitat'><p> We started our VNA project in February 2021 to replace our  PACS and implement innovative workflows with the INFINITT  Healthcare Platform (IHP). A key factor in the success of the  project was INFINITT's ability to adapt to the very speci\ufb01c  technical and organizational environment of HUG.  Continuous adjustments were made to achieve the best  possible results and make the most of all potential. <\/p><\/div><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-name'><p> Nicolas Roduit, PhD <\/p><\/div><div class='slide-entry-position'><p> Leitender Softwarearchitekt, Universit\u00e4tsspital Genf (HUG)  <\/p><\/div><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>\/wp-content\/uploads\/2023\/11\/ieu_logo_blue.svg<\/span>\n\t\t\t\t\t\t<span itemprop='height'>0<\/span>\n\t\t\t\t\t\t<span itemprop='width'>0<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>econsor<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>\/wp-content\/uploads\/2023\/11\/ieu_logo_blue.svg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>econsor<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2024-04-25T16:01:40+02:00\" >2023-12-20 09:46:27<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-07-29 10:25:30<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>HUG<\/span><\/span><\/span><\/li><\/ul><\/div><\/div><script type=\"text\/javascript\">\n\n\t\t\t\t\t\t\t\tjQuery(window).on(\"load\",function() {\n\t\t\t\t\t\t\t\t\tnew Splide( \"#splide-postslider-16904629\" ).mount();\n\t\t\t\t\t\t\t\t});\n\t\t\t\t\t\t<\/script>\n<div  class='hr av-48iht3-69d8890dca973d448c30f576368f8902 hr-full  avia-builder-el-69  el_after_econsor_postslider  avia-builder-el-last  hr-no-shadow'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/div>\n\n\n[av_section min_height='' min_height_pc='25' min_height_px='500px' shadow='no-border-styling' bottom_border='no-border-styling' bottom_border_diagonal_color='#333333' bottom_border_diagonal_direction='' bottom_border_style='' padding='default' custom_margin='0px' custom_margin_sync='true' av-desktop-custom_margin='' av-desktop-custom_margin_sync='true' av-medium-custom_margin='' av-medium-custom_margin_sync='true' av-small-custom_margin='' av-small-custom_margin_sync='true' av-mini-custom_margin='' av-mini-custom_margin_sync='true' svg_div_top='' svg_div_top_color='#333333' svg_div_top_width='100' svg_div_top_height='50' svg_div_top_max_height='none' svg_div_top_opacity='' svg_div_bottom='' svg_div_bottom_color='#333333' svg_div_bottom_width='100' svg_div_bottom_height='50' svg_div_bottom_max_height='none' svg_div_bottom_opacity='' fold_type='' fold_height='' fold_more='Weiterlesen' fold_less='Read less' fold_text_style='' fold_btn_align='' color='main_color' background='bg_color' custom_bg='' background_gradient_direction='vertical' background_gradient_color1='#000000' background_gradient_color2='#ffffff' background_gradient_color3='' src='' attachment='' attachment_size='' attach='scroll' position='top left' repeat='no-repeat' video='' video_ratio='16:9' overlay_opacity='0.5' overlay_color='' overlay_pattern='' overlay_custom_pattern='' custom_arrow_bg='' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' fold_timer='' z_index_fold='' css_position_z_index='' av-desktop-css_position_z_index='' av-medium-css_position_z_index='' av-small-css_position_z_index='' av-mini-css_position_z_index='' id='' custom_class='text-video' template_class='' aria_label='' element_template='' one_element_template='' av_element_hidden_in_editor='0' av_uid='av-hg1757' sc_version='1.0']\n[av_one_half first min_height='' vertical_alignment='av-align-top' space='' row_boxshadow='' row_boxshadow_width='10' row_boxshadow_color='' custom_margin='' margin='0px' av-desktop-margin='' av-medium-margin='' av-small-margin='' av-mini-margin='' mobile_breaking='' mobile_column_order='' border='' border_style='solid' border_color='' radius='' min_col_height='' padding='' av-desktop-padding='' av-medium-padding='' av-small-padding='' av-mini-padding='' svg_div_top='' svg_div_top_color='#333333' svg_div_top_width='100' svg_div_top_height='50' svg_div_top_max_height='none' svg_div_top_flip='' svg_div_top_invert='' svg_div_top_front='' svg_div_top_opacity='' svg_div_top_preview='' svg_div_bottom='' svg_div_bottom_color='#333333' svg_div_bottom_width='100' svg_div_bottom_height='50' svg_div_bottom_max_height='none' svg_div_bottom_flip='' svg_div_bottom_invert='' svg_div_bottom_front='' svg_div_bottom_opacity='' svg_div_bottom_preview='' fold_type='' fold_height='' fold_more='Weiterlesen' fold_less='Read less' fold_text_style='' fold_btn_align='' column_boxshadow='' column_boxshadow_width='10' column_boxshadow_color='' background='bg_color' background_color='' background_gradient_direction='vertical' background_gradient_color1='#000000' background_gradient_color2='#ffffff' background_gradient_color3='' src='' background_position='top left' background_repeat='no-repeat' highlight='' highlight_size='' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' animation='' animation_duration='' animation_custom_bg_color='' animation_z_index_curtain='100' parallax_parallax='' parallax_parallax_speed='' av-desktop-parallax_parallax='' av-desktop-parallax_parallax_speed='' av-medium-parallax_parallax='' av-medium-parallax_parallax_speed='' av-small-parallax_parallax='' av-small-parallax_parallax_speed='' av-mini-parallax_parallax='' av-mini-parallax_parallax_speed='' fold_timer='' z_index_fold='' css_position='' css_position_location='' css_position_z_index='' av-desktop-css_position='' av-desktop-css_position_location='' av-desktop-css_position_z_index='' av-medium-css_position='' av-medium-css_position_location='' av-medium-css_position_z_index='' av-small-css_position='' av-small-css_position_location='' av-small-css_position_z_index='' av-mini-css_position='' av-mini-css_position_location='' av-mini-css_position_z_index='' link='' linktarget='' link_hover='' title_attr='' alt_attr='' mobile_display='' mobile_col_pos='0' id='' custom_class='' template_class='' aria_label='' element_template='' one_element_template='' show_locked_options_fakearg='' av_uid='av-g2yngr' sc_version='1.0']\n[av_heading heading='Zarz\u0105dzanie danymi obraz\u00f3w medycznych jest w naszym DNA' tag='h2' style='' subheading_active='' show_icon='' icon='ue800' font='entypo-fontello' size='' av-desktop-font-size-title='' av-medium-font-size-title='' av-small-font-size-title='' av-mini-font-size-title='' subheading_size='' av-desktop-font-size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' icon_size='' av-desktop-font-size-1='' av-medium-font-size-1='' av-small-font-size-1='' av-mini-font-size-1='' color='' custom_font='' subheading_color='' seperator_color='' icon_color='' margin='' margin_sync='true' av-desktop-margin='' av-desktop-margin_sync='true' av-medium-margin='' av-medium-margin_sync='true' av-small-margin='' av-small-margin_sync='true' av-mini-margin='' av-mini-margin_sync='true' headline_padding='' headline_padding_sync='true' av-desktop-headline_padding='' av-desktop-headline_padding_sync='true' av-medium-headline_padding='' av-medium-headline_padding_sync='true' av-small-headline_padding='' av-small-headline_padding_sync='true' av-mini-headline_padding='' av-mini-headline_padding_sync='true' padding='10' av-desktop-padding='' av-medium-padding='' av-small-padding='' av-mini-padding='' icon_padding='10' av-desktop-icon_padding='' av-medium-icon_padding='' av-small-icon_padding='' av-mini-icon_padding='' link='' link_target='' title_attr='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-ec6a0b' sc_version='1.0' admin_preview_bg=''][\/av_heading]\n\n[av_textblock fold_type='' fold_height='' fold_more='Weiterlesen' fold_less='Read less' fold_text_style='' fold_btn_align='' textblock_styling_align='' textblock_styling='' textblock_styling_gap='' textblock_styling_mobile='' size='' av-desktop-font-size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' font_color='' color='' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' fold_timer='' z_index_fold='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-buebp7' sc_version='1.0' admin_preview_bg='']\nOd ponad 20 lat podstawow\u0105 kompetencj\u0105 INFINITT jest rozw\u00f3j oprogramowania do obrazowania diagnostycznego, dzi\u0119ki czemu ponad 6500 klient\u00f3w w ponad 55 krajach korzysta obecnie z innowacyjnych rozwi\u0105za\u0144 INFINITT.\nZaufaj naszemu wieloletniemu do\u015bwiadczeniu i skorzystaj z naszych najwy\u017cszej klasy us\u0142ug.\n[\/av_textblock]\n\n[av_toggle_container faq_markup='faq_markup' initial='1' mode='toggle' sort='' styling='' colors='custom' font_color='#000000' background_color='' border_color='#000000' toggle_icon_color='#0060a5' colors_current='custom' font_color_current='' toggle_icon_color_current='#72246c' background_current='' background_color_current='' background_gradient_current_direction='vertical' background_gradient_current_color1='#000000' background_gradient_current_color2='#ffffff' background_gradient_current_color3='' hover_colors='' hover_font_color='' hover_background_color='' hover_toggle_icon_color='' size-toggle='' av-desktop-font-size-toggle='' av-medium-font-size-toggle='' av-small-font-size-toggle='' av-mini-font-size-toggle='' size-content='' av-desktop-font-size-content='' av-medium-font-size-content='' av-small-font-size-content='' av-mini-font-size-content='' heading_tag='' heading_class='' alb_description='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-ly4l90f0' sc_version='1.0' admin_preview_bg='']\n[av_toggle title='Oferujemy niestandardowe rozwi\u0105zania programowe, kt\u00f3re s\u0105 konsekwentnie dostosowywane do Twoich potrzeb' tags='' custom_id='' element_template='' one_element_template='' av_uid='av-5mihdn' sc_version='1.0']\nRozwi\u0105zania INFINITT do obrazowania medycznego s\u0105 wiod\u0105ce pod wzgl\u0119dem technologicznym i imponuj\u0105 wysok\u0105 u\u017cyteczno\u015bci\u0105, zoptymalizowanymi przep\u0142ywami pracy i wsparciem sztucznej inteligencji.\nWdra\u017camy nasze rozwi\u0105zania w spos\u00f3b indywidualny i dostosowany do potrzeb klienta, zapewniaj\u0105c profesjonalne wsparcie przez ca\u0142y cykl \u017cycia produktu.\nPodczas opracowywania produkt\u00f3w przywi\u0105zujemy du\u017c\u0105 wag\u0119 do funkcji produktu, kt\u00f3re wspieraj\u0105 precyzyjn\u0105 i szybk\u0105 diagnoz\u0119, a tym samym przyczyniaj\u0105 si\u0119 do optymalnego leczenia pacjent\u00f3w.\nNasze rozwi\u0105zania w zakresie obrazowania dostosowuj\u0105 si\u0119 do struktur Twojej praktyki lub \u015brodowiska kliniki i mo\u017cna je \u0142atwo rozszerzy\u0107 o nowe urz\u0105dzenia, dodatkowe oddzia\u0142y i lokalizacje.\n[\/av_toggle]\n[av_toggle title='Nasze us\u0142ugi nie ko\u0144cz\u0105 si\u0119 na Twojej satysfakcji' tags='' custom_id='' element_template='' one_element_template='' av_uid='av-4bdlez' sc_version='1.0']\nCa\u0142y zesp\u00f3\u0142 INFINITT Europe pracuje z do\u015bwiadczeniem i pasj\u0105 ka\u017cdego dnia, aby zapewni\u0107 naszym klientom najlepsz\u0105 obs\u0142ug\u0119 i wsparcie w celu wspierania optymalnej opieki medycznej dla pacjent\u00f3w.\n[\/av_toggle]\n[av_toggle title='INFINITT jest wiod\u0105cym globalnym i bezpiecznym dostawc\u0105 oprogramowania do obrazowania medycznego' tags='' custom_id='' element_template='' one_element_template='' av_uid='av-381hh7' sc_version='1.0']\nJako pionier PACS, INFINITT opracowuje rozwi\u0105zania informatyczne do zarz\u0105dzania obrazami i danymi w radiologii od 2002 roku.\nOd samego pocz\u0105tku INFINITT koncentrowa\u0142 si\u0119 na oprogramowaniu do obrazowania diagnostycznego.\nZ biegiem lat firma zbudowa\u0142a unikalne kompetencje rynkowe i produktowe, a tak\u017ce wiedz\u0119 specjalistyczn\u0105 w powi\u0105zanych obszarach, takich jak bezpiecze\u0144stwo IT.\n[\/av_toggle]\n[\/av_toggle_container]\n[\/av_one_half][av_one_half min_height='' vertical_alignment='av-align-top' space='' row_boxshadow='' row_boxshadow_width='10' row_boxshadow_color='' custom_margin='' margin='0px' av-desktop-margin='' av-medium-margin='' av-small-margin='' av-mini-margin='' mobile_breaking='' mobile_column_order='' border='' border_style='solid' border_color='' radius='' min_col_height='' padding='' av-desktop-padding='' av-medium-padding='' av-small-padding='' av-mini-padding='' svg_div_top='' svg_div_top_color='#333333' svg_div_top_width='100' svg_div_top_height='50' svg_div_top_max_height='none' svg_div_top_flip='' svg_div_top_invert='' svg_div_top_front='' svg_div_top_opacity='' svg_div_top_preview='' svg_div_bottom='' svg_div_bottom_color='#333333' svg_div_bottom_width='100' svg_div_bottom_height='50' svg_div_bottom_max_height='none' svg_div_bottom_flip='' svg_div_bottom_invert='' svg_div_bottom_front='' svg_div_bottom_opacity='' svg_div_bottom_preview='' fold_type='' fold_height='' fold_more='Weiterlesen' fold_less='Read less' fold_text_style='' fold_btn_align='' column_boxshadow='' column_boxshadow_width='10' column_boxshadow_color='' background='bg_color' background_color='' background_gradient_direction='vertical' background_gradient_color1='#000000' background_gradient_color2='#ffffff' background_gradient_color3='' src='' background_position='top left' background_repeat='no-repeat' highlight='' highlight_size='' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' animation='' animation_duration='' animation_custom_bg_color='' animation_z_index_curtain='100' parallax_parallax='' parallax_parallax_speed='' av-desktop-parallax_parallax='' av-desktop-parallax_parallax_speed='' av-medium-parallax_parallax='' av-medium-parallax_parallax_speed='' av-small-parallax_parallax='' av-small-parallax_parallax_speed='' av-mini-parallax_parallax='' av-mini-parallax_parallax_speed='' fold_timer='' z_index_fold='' css_position='' css_position_location='' css_position_z_index='' av-desktop-css_position='' av-desktop-css_position_location='' av-desktop-css_position_z_index='' av-medium-css_position='' av-medium-css_position_location='' av-medium-css_position_z_index='' av-small-css_position='' av-small-css_position_location='' av-small-css_position_z_index='' av-mini-css_position='' av-mini-css_position_location='' av-mini-css_position_z_index='' link='' linktarget='' link_hover='' title_attr='' alt_attr='' mobile_display='' mobile_col_pos='0' id='' custom_class='' template_class='' aria_label='' element_template='' one_element_template='' show_locked_options_fakearg='' av_uid='av-49pkx7' sc_version='1.0']\n[av_video src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/01\/INFINITT-Healthcare-corporate-video-ENG.mp4\" mobile_image=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/07\/Video-Vorschau-Website.png\" attachment=\"5283\" attachment_size=\"full\" format=\"16-9\" width=\"16\" height=\"9\" conditional_play=\"\" id=\"\" custom_class=\"\" template_class=\"\" element_template=\"\" one_element_template=\"\" av_uid=\"av-2kaxl7\" sc_version=\"1.0\"]\n[\/av_one_half]\n[\/av_section][av_section min_height='' min_height_pc='25' min_height_px='500px' shadow='no-border-styling' bottom_border='no-border-styling' bottom_border_diagonal_color='#333333' bottom_border_diagonal_direction='' bottom_border_style='' padding='default' custom_margin='0px' custom_margin_sync='true' av-desktop-custom_margin='' av-desktop-custom_margin_sync='true' av-medium-custom_margin='' av-medium-custom_margin_sync='true' av-small-custom_margin='' av-small-custom_margin_sync='true' av-mini-custom_margin='' av-mini-custom_margin_sync='true' svg_div_top='' svg_div_top_color='#333333' svg_div_top_width='100' svg_div_top_height='50' svg_div_top_max_height='none' svg_div_top_opacity='' svg_div_bottom='' svg_div_bottom_color='#333333' svg_div_bottom_width='100' svg_div_bottom_height='50' svg_div_bottom_max_height='none' svg_div_bottom_opacity='' fold_type='' fold_height='' fold_more='Weiterlesen' fold_less='Read less' fold_text_style='' fold_btn_align='' color='main_color' background='bg_color' custom_bg='' background_gradient_direction='vertical' background_gradient_color1='#000000' background_gradient_color2='#ffffff' background_gradient_color3='' src='' attachment='' attachment_size='' attach='scroll' position='top left' repeat='no-repeat' video='' video_ratio='16:9' overlay_opacity='0.5' overlay_color='' overlay_pattern='' overlay_custom_pattern='' custom_arrow_bg='' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' fold_timer='' z_index_fold='' css_position_z_index='' av-desktop-css_position_z_index='' av-medium-css_position_z_index='' av-small-css_position_z_index='' av-mini-css_position_z_index='' id='' custom_class='partner-slider' template_class='' aria_label='' element_template='' one_element_template='' av_element_hidden_in_editor='0' av_uid='av-bzc0az' sc_version='1.0']\n[av_one_full first min_height='' vertical_alignment='av-align-top' space='' row_boxshadow_width='10' row_boxshadow_color='' margin='0px' margin_sync='true' av-desktop-margin='' av-desktop-margin_sync='true' av-medium-margin='' av-medium-margin_sync='true' av-small-margin='' av-small-margin_sync='true' av-mini-margin='' av-mini-margin_sync='true' mobile_breaking='' mobile_column_order='' border='' border_style='solid' border_color='' radius='' radius_sync='true' min_col_height='' padding='' padding_sync='true' av-desktop-padding='' av-desktop-padding_sync='true' av-medium-padding='' av-medium-padding_sync='true' av-small-padding='' av-small-padding_sync='true' av-mini-padding='' av-mini-padding_sync='true' svg_div_top='' svg_div_top_color='#333333' svg_div_top_width='100' svg_div_top_height='50' svg_div_top_max_height='none' svg_div_top_opacity='' svg_div_bottom='' svg_div_bottom_color='#333333' svg_div_bottom_width='100' svg_div_bottom_height='50' svg_div_bottom_max_height='none' svg_div_bottom_opacity='' fold_type='' fold_height='' fold_more='Weiterlesen' fold_less='Read less' fold_text_style='' fold_btn_align='' column_boxshadow_width='10' column_boxshadow_color='' background='bg_color' background_color='' background_gradient_direction='vertical' background_gradient_color1='#000000' background_gradient_color2='#ffffff' background_gradient_color3='' src='' attachment='' attachment_size='' background_position='top left' background_repeat='no-repeat' highlight_size='1.1' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' animation='' animation_duration='' animation_custom_bg_color='' animation_z_index_curtain='100' parallax_parallax='' parallax_parallax_speed='' av-desktop-parallax_parallax='' av-desktop-parallax_parallax_speed='' av-medium-parallax_parallax='' av-medium-parallax_parallax_speed='' av-small-parallax_parallax='' av-small-parallax_parallax_speed='' av-mini-parallax_parallax='' av-mini-parallax_parallax_speed='' fold_timer='' z_index_fold='' css_position='' css_position_location=',,,' css_position_z_index='' av-desktop-css_position='' av-desktop-css_position_location=',,,' av-desktop-css_position_z_index='' av-medium-css_position='' av-medium-css_position_location=',,,' av-medium-css_position_z_index='' av-small-css_position='' av-small-css_position_location=',,,' av-small-css_position_z_index='' av-mini-css_position='' av-mini-css_position_location=',,,' av-mini-css_position_z_index='' link='' linktarget='' link_hover='' title_attr='' alt_attr='' mobile_display='' mobile_col_pos='0' id='' custom_class='' template_class='' aria_label='' element_template='' one_element_template='' av_uid='av-avxjhn' sc_version='1.0']\n[econsor_contentslider heading=\"\" columns=\"6\" maintain_columns=\"false\" columnfocus=\"center\" pagination=\"false\" gap=\"big\" font_color=\"\" color=\"\" background=\"bg_color\" custom_bg=\"\" background_gradient_color1=\"\" background_gradient_color2=\"\" background_gradient_direction=\"vertical\" heading_tag=\"\" heading_class=\"\" econsor_contentslider=\"\" custom_class=\"partner-slider-full\" template_class=\"\" av_uid=\"av-lxvlgpvt\" sc_version=\"1.0\"]\n[econsor_contentslide title=\"Microsoft\" date=\"\" custom_width=\"1\" show_btn=\"false\" show_customicon=\"false\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/Microsoft-Partner_2.png\" attachment=\"3454\" attachment_size=\"full\" heading_tag=\"\" heading_class=\"\" link=\"\" linktarget=\"\" label=\"Kliknij mnie\" btn_iselect=\"yes\" icon=\"ue800\" font=\",\" size=\"small\" label_display=\"\" title_attr=\"\" btn_custom_class=\"\" color=\"theme-color\" customicon=\"ue800\" customiconsize=\"40px\" icon_color=\"#ffffff\" av_uid=\"av-9syaij\" sc_version=\"1.0\"][\/econsor_contentslide]\n[econsor_contentslide title=\"LG\" date=\"\" custom_width=\"1\" show_btn=\"false\" show_customicon=\"false\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/LG_1.png\" attachment=\"3450\" attachment_size=\"full\" heading_tag=\"\" heading_class=\"\" link=\"\" linktarget=\"\" label=\"Kliknij mnie\" btn_iselect=\"yes\" icon=\"ue800\" font=\",\" size=\"small\" label_display=\"\" title_attr=\"\" btn_custom_class=\"\" color=\"theme-color\" customicon=\"ue800\" customiconsize=\"40px\" icon_color=\"#ffffff\" av_uid=\"av-7xlya3\" sc_version=\"1.0\"][\/econsor_contentslide]\n[econsor_contentslide title=\"Eizo\" date=\"\" custom_width=\"1\" show_btn=\"false\" show_customicon=\"false\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/EIZO.png\" attachment=\"3446\" attachment_size=\"full\" heading_tag=\"\" heading_class=\"\" link=\"\" linktarget=\"\" label=\"Kliknij mnie\" btn_iselect=\"yes\" icon=\"ue800\" font=\",\" size=\"small\" label_display=\"\" title_attr=\"\" btn_custom_class=\"\" color=\"theme-color\" customicon=\"ue800\" customiconsize=\"40px\" icon_color=\"#ffffff\" av_uid=\"av-59sg6j\" sc_version=\"1.0\"][\/econsor_contentslide]\n[econsor_contentslide title=\"Barco\" date=\"\" custom_width=\"1\" show_btn=\"false\" show_customicon=\"false\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/BARCO_rgb_primarylogo_red-1.png\" attachment=\"3442\" attachment_size=\"full\" heading_tag=\"\" heading_class=\"\" link=\"\" linktarget=\"\" label=\"Kliknij mnie\" btn_iselect=\"yes\" icon=\"ue800\" font=\",\" size=\"small\" label_display=\"\" title_attr=\"\" btn_custom_class=\"\" color=\"theme-color\" customicon=\"ue800\" customiconsize=\"40px\" icon_color=\"#ffffff\" av_uid=\"av-4ksghn\" sc_version=\"1.0\"][\/econsor_contentslide]\n[econsor_contentslide title=\"Oracle\" date=\"\" custom_width=\"1\" show_btn=\"false\" show_customicon=\"false\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/06\/Oracle-Logo_40.png\" attachment=\"4711\" attachment_size=\"full\" heading_tag=\"\" heading_class=\"\" link=\"\" linktarget=\"\" label=\"Kliknij mnie\" btn_iselect=\"yes\" icon=\"ue800\" font=\",\" size=\"small\" label_display=\"\" title_attr=\"\" btn_custom_class=\"\" color=\"theme-color\" customicon=\"ue800\" customiconsize=\"40px\" icon_color=\"#ffffff\" av_uid=\"av-353tgr\" sc_version=\"1.0\"][\/econsor_contentslide]\n[econsor_contentslide title=\"Oczywiste\" date=\"\" custom_width=\"1\" show_btn=\"false\" show_customicon=\"false\" src=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/07\/Evident_Logo_Color_40.png\" attachment=\"5106\" attachment_size=\"full\" heading_tag=\"\" heading_class=\"\" link=\"\" linktarget=\"\" label=\"Kliknij mnie\" btn_iselect=\"yes\" icon=\"ue800\" font=\",\" size=\"small\" label_display=\"\" title_attr=\"\" btn_custom_class=\"\" color=\"theme-color\" customicon=\"ue800\" customiconsize=\"40px\" icon_color=\"#ffffff\" av_uid=\"av-353tgr-1\" sc_version=\"1.0\"][\/econsor_contentslide]\n[\/econsor_contentslider]\n[\/av_one_full]\n[\/av_section]\n\n\n\n[av_section min_height='' min_height_pc='25' min_height_px='500px' shadow='no-border-styling' bottom_border='no-border-styling' bottom_border_diagonal_color='#333333' bottom_border_diagonal_direction='' bottom_border_style='' padding='default' custom_margin='0px' custom_margin_sync='true' av-desktop-custom_margin='' av-desktop-custom_margin_sync='true' av-medium-custom_margin='' av-medium-custom_margin_sync='true' av-small-custom_margin='' av-small-custom_margin_sync='true' av-mini-custom_margin='' av-mini-custom_margin_sync='true' svg_div_top='' svg_div_top_color='#333333' svg_div_top_width='100' svg_div_top_height='50' svg_div_top_max_height='none' svg_div_top_opacity='' svg_div_bottom='' svg_div_bottom_color='#333333' svg_div_bottom_width='100' svg_div_bottom_height='50' svg_div_bottom_max_height='none' svg_div_bottom_opacity='' fold_type='' fold_height='' fold_more='Weiterlesen' fold_less='Read less' fold_text_style='' fold_btn_align='' color='main_color' background='bg_color' custom_bg='' background_gradient_direction='vertical' background_gradient_color1='#000000' background_gradient_color2='#ffffff' background_gradient_color3='' src='' attachment='' attachment_size='' attach='scroll' position='top left' repeat='no-repeat' video='' video_ratio='16:9' overlay_opacity='0.5' overlay_color='' overlay_pattern='' overlay_custom_pattern='' custom_arrow_bg='' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' fold_timer='' z_index_fold='' css_position_z_index='' av-desktop-css_position_z_index='' av-medium-css_position_z_index='' av-small-css_position_z_index='' av-mini-css_position_z_index='' id='' custom_class='contact-sektion' template_class='' aria_label='' element_template='' one_element_template='' av_element_hidden_in_editor='0' av_uid='av-1ezw2c' sc_version='1.0']\r\n\r\n[av_one_half first min_height='av-equal-height-column' vertical_alignment='av-align-top' space='no_margin' row_boxshadow_width='10' row_boxshadow_color='' margin='0px' margin_sync='true' av-desktop-margin='' av-desktop-margin_sync='true' av-medium-margin='' av-medium-margin_sync='true' av-small-margin='' av-small-margin_sync='true' av-mini-margin='' av-mini-margin_sync='true' mobile_breaking='' mobile_column_order='' border='' border_style='solid' border_color='' radius='' radius_sync='true' min_col_height='' padding='' padding_sync='true' av-desktop-padding='' av-desktop-padding_sync='true' av-medium-padding='' av-medium-padding_sync='true' av-small-padding='' av-small-padding_sync='true' av-mini-padding='' av-mini-padding_sync='true' svg_div_top='' svg_div_top_color='#333333' svg_div_top_width='100' svg_div_top_height='50' svg_div_top_max_height='none' svg_div_top_opacity='' svg_div_bottom='' svg_div_bottom_color='#333333' svg_div_bottom_width='100' svg_div_bottom_height='50' svg_div_bottom_max_height='none' svg_div_bottom_opacity='' fold_type='' fold_height='' fold_more='Weiterlesen' fold_less='Read less' fold_text_style='' fold_btn_align='' column_boxshadow_width='10' column_boxshadow_color='' background='bg_color' background_color='' background_gradient_direction='vertical' background_gradient_color1='#000000' background_gradient_color2='#ffffff' background_gradient_color3='' src='' attachment='' attachment_size='' background_position='top left' background_repeat='no-repeat' highlight_size='1.1' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' animation='' animation_duration='' animation_custom_bg_color='' animation_z_index_curtain='100' parallax_parallax='' parallax_parallax_speed='' av-desktop-parallax_parallax='' av-desktop-parallax_parallax_speed='' av-medium-parallax_parallax='' av-medium-parallax_parallax_speed='' av-small-parallax_parallax='' av-small-parallax_parallax_speed='' av-mini-parallax_parallax='' av-mini-parallax_parallax_speed='' fold_timer='' z_index_fold='' css_position='' css_position_location=',,,' css_position_z_index='' av-desktop-css_position='' av-desktop-css_position_location=',,,' av-desktop-css_position_z_index='' av-medium-css_position='' av-medium-css_position_location=',,,' av-medium-css_position_z_index='' av-small-css_position='' av-small-css_position_location=',,,' av-small-css_position_z_index='' av-mini-css_position='' av-mini-css_position_location=',,,' av-mini-css_position_z_index='' link='' linktarget='' link_hover='' title_attr='' alt_attr='' mobile_display='' mobile_col_pos='0' id='' custom_class='contact-form-column' template_class='' aria_label='' element_template='' one_element_template='' av_uid='av-1bgg3o' sc_version='1.0']\r\n\r\n[av_heading heading='Napisz do nas wiadomo\u015b\u0107' tag='h3' style='' subheading_active='' show_icon='' icon='ue800' font='entypo-fontello' size='' av-desktop-font-size-title='' av-medium-font-size-title='' av-small-font-size-title='' av-mini-font-size-title='' subheading_size='' av-desktop-font-size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' icon_size='' av-desktop-font-size-1='' av-medium-font-size-1='' av-small-font-size-1='' av-mini-font-size-1='' color='' custom_font='' subheading_color='' seperator_color='' icon_color='' margin='' margin_sync='true' av-desktop-margin='' av-desktop-margin_sync='true' av-medium-margin='' av-medium-margin_sync='true' av-small-margin='' av-small-margin_sync='true' av-mini-margin='' av-mini-margin_sync='true' headline_padding='' headline_padding_sync='true' av-desktop-headline_padding='' av-desktop-headline_padding_sync='true' av-medium-headline_padding='' av-medium-headline_padding_sync='true' av-small-headline_padding='' av-small-headline_padding_sync='true' av-mini-headline_padding='' av-mini-headline_padding_sync='true' padding='10' av-desktop-padding='' av-medium-padding='' av-small-padding='' av-mini-padding='' icon_padding='10' av-desktop-icon_padding='' av-medium-icon_padding='' av-small-icon_padding='' av-mini-icon_padding='' link='' link_target='' title_attr='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-3gpp3o' sc_version='1.0' admin_preview_bg=''][\/av_heading]\r\n\r\n[av_textblock fold_type='' fold_height='' fold_more='Weiterlesen' fold_less='Read less' fold_text_style='' fold_btn_align='' textblock_styling_align='' textblock_styling='' textblock_styling_gap='' textblock_styling_mobile='' size='' av-desktop-font-size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' font_color='' color='' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' fold_timer='' z_index_fold='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-37aomk' sc_version='1.0' admin_preview_bg='']\r\nDaj nam zna\u0107, jak mo\u017cemy Ci pom\u00f3c, a skontaktujemy si\u0119 z Tob\u0105 tak szybko, jak to mo\u017cliwe.\r\n[\/av_textblock]\r\n\r\n[av_codeblock wrapper_element='' wrapper_element_attributes='' codeblock_type='' alb_description='' id='' custom_class='' template_class='' av_uid='av-315sgs' sc_version='1.0']\r\n[gravityform id=\"9\" title=\"true\"]\r\n[\/av_codeblock]\r\n\r\n[\/av_one_half][av_one_half min_height='' vertical_alignment='av-align-top' space='' row_boxshadow_width='10' row_boxshadow_color='' margin='0px' margin_sync='true' av-desktop-margin='' av-desktop-margin_sync='true' av-medium-margin='' av-medium-margin_sync='true' av-small-margin='' av-small-margin_sync='true' av-mini-margin='' av-mini-margin_sync='true' mobile_breaking='' mobile_column_order='' border='' border_style='solid' border_color='' radius='' radius_sync='true' min_col_height='' padding='' padding_sync='true' av-desktop-padding='' av-desktop-padding_sync='true' av-medium-padding='' av-medium-padding_sync='true' av-small-padding='' av-small-padding_sync='true' av-mini-padding='' av-mini-padding_sync='true' svg_div_top='' svg_div_top_color='#333333' svg_div_top_width='100' svg_div_top_height='50' svg_div_top_max_height='none' svg_div_top_opacity='' svg_div_bottom='' svg_div_bottom_color='#333333' svg_div_bottom_width='100' svg_div_bottom_height='50' svg_div_bottom_max_height='none' svg_div_bottom_opacity='' fold_type='' fold_height='' fold_more='Weiterlesen' fold_less='Read less' fold_text_style='' fold_btn_align='' column_boxshadow_width='10' column_boxshadow_color='' background='bg_color' background_color='' background_gradient_direction='vertical' background_gradient_color1='#000000' background_gradient_color2='#ffffff' background_gradient_color3='' src='' attachment='' attachment_size='' background_position='top left' background_repeat='no-repeat' highlight_size='1.1' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' animation='' animation_duration='' animation_custom_bg_color='' animation_z_index_curtain='100' parallax_parallax='' parallax_parallax_speed='' av-desktop-parallax_parallax='' av-desktop-parallax_parallax_speed='' av-medium-parallax_parallax='' av-medium-parallax_parallax_speed='' av-small-parallax_parallax='' av-small-parallax_parallax_speed='' av-mini-parallax_parallax='' av-mini-parallax_parallax_speed='' fold_timer='' z_index_fold='' css_position='' css_position_location=',,,' css_position_z_index='' av-desktop-css_position='' av-desktop-css_position_location=',,,' av-desktop-css_position_z_index='' av-medium-css_position='' av-medium-css_position_location=',,,' av-medium-css_position_z_index='' av-small-css_position='' av-small-css_position_location=',,,' av-small-css_position_z_index='' av-mini-css_position='' av-mini-css_position_location=',,,' av-mini-css_position_z_index='' link='' linktarget='' link_hover='' title_attr='' alt_attr='' mobile_display='' mobile_col_pos='0' id='' custom_class='contact-info-column' template_class='' aria_label='' element_template='' one_element_template='' av_uid='av-v4z6k' sc_version='1.0']\r\n\r\n[av_heading heading='Wsparcie techniczne Polska' tag='h3' style='' subheading_active='' show_icon='' icon='ue800' font='entypo-fontello' size='' av-desktop-font-size-title='' av-medium-font-size-title='' av-small-font-size-title='' av-mini-font-size-title='' subheading_size='' av-desktop-font-size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' icon_size='' av-desktop-font-size-1='' av-medium-font-size-1='' av-small-font-size-1='' av-mini-font-size-1='' color='' custom_font='' subheading_color='' seperator_color='' icon_color='' margin='' margin_sync='true' av-desktop-margin='' av-desktop-margin_sync='true' av-medium-margin='' av-medium-margin_sync='true' av-small-margin='' av-small-margin_sync='true' av-mini-margin='' av-mini-margin_sync='true' headline_padding='' headline_padding_sync='true' av-desktop-headline_padding='' av-desktop-headline_padding_sync='true' av-medium-headline_padding='' av-medium-headline_padding_sync='true' av-small-headline_padding='' av-small-headline_padding_sync='true' av-mini-headline_padding='' av-mini-headline_padding_sync='true' padding='10' av-desktop-padding='' av-medium-padding='' av-small-padding='' av-mini-padding='' icon_padding='10' av-desktop-icon_padding='' av-medium-icon_padding='' av-small-icon_padding='' av-mini-icon_padding='' link='' link_target='' title_attr='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-lp8g1gwh' sc_version='1.0' admin_preview_bg=''][\/av_heading]\r\n\r\n[av_textblock fold_type='' fold_height='' fold_more='Weiterlesen' fold_less='Read less' fold_text_style='' fold_btn_align='' textblock_styling_align='' textblock_styling='' textblock_styling_gap='' textblock_styling_mobile='' size='' av-desktop-font-size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' font_color='' color='' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' fold_timer='' z_index_fold='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-2x33lo' sc_version='1.0' admin_preview_bg='']\r\nJeste\u015b ju\u017c naszym klientem i masz problem techniczny?\r\nNasi eksperci s\u0105 do Twojej dyspozycji!\r\n[\/av_textblock]\r\n\r\n[av_buttonrow alignment='left' button_spacing='5' button_spacing_unit='px' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' text-padding='' text-padding_sync='true' av-desktop-text-padding='' av-desktop-text-padding_sync='true' av-medium-text-padding='' av-medium-text-padding_sync='true' av-small-text-padding='' av-small-text-padding_sync='true' av-mini-text-padding='' av-mini-text-padding_sync='true' alb_description='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-m1em5uti' sc_version='1.0' admin_preview_bg='']\r\n[av_buttonrow_item label='hd@grupaq.pl' icon_select='yes' icon='ue921' font='infinitt-icons' link='manually,support@infinitteu.com' link_target='' size='small' label_display='' title_attr='' size-text='' av-desktop-font-size-text='' av-medium-font-size-text='' av-small-font-size-text='' av-mini-font-size-text='' btn-padding='' btn-padding_sync='true' av-desktop-btn-padding='' av-desktop-btn-padding_sync='true' av-medium-btn-padding='' av-medium-btn-padding_sync='true' av-small-btn-padding='' av-small-btn-padding_sync='true' av-mini-btn-padding='' av-mini-btn-padding_sync='true' color_options='' color='light' custom_bg='#444444' custom_font='#ffffff' btn_color_bg='theme-color' btn_custom_grad_direction='vertical' btn_custom_grad_1='#000000' btn_custom_grad_2='#ffffff' btn_custom_grad_3='' btn_custom_grad_opacity='0.7' btn_custom_bg='#444444' btn_color_bg_hover='theme-color-highlight' btn_custom_bg_hover='#444444' btn_color_font='theme-color' btn_custom_font='#ffffff' btn_color_font_hover='white' btn_custom_font_hover='#ffffff' border='' border_width='' border_width_sync='true' border_color='' border_radius='' border_radius_sync='true' box_shadow='' box_shadow_style='0px,0px,0px,0px' box_shadow_color='' hover_opacity='' sonar_effect_effect='' sonar_effect_color='' sonar_effect_duration='1' sonar_effect_scale='' sonar_effect_opac='0.5' element_template='' one_element_template='' av_uid='av-m1em5gia' sc_version='1.0']\r\n[av_buttonrow_item label='+48 663 336 962' icon_select='yes' icon='ue916' font='infinitt-icons' link='manually,tel:+4969583000300' link_target='' size='small' label_display='' title_attr='' size-text='' av-desktop-font-size-text='' av-medium-font-size-text='' av-small-font-size-text='' av-mini-font-size-text='' btn-padding='' btn-padding_sync='true' av-desktop-btn-padding='' av-desktop-btn-padding_sync='true' av-medium-btn-padding='' av-medium-btn-padding_sync='true' av-small-btn-padding='' av-small-btn-padding_sync='true' av-mini-btn-padding='' av-mini-btn-padding_sync='true' color_options='' color='light' custom_bg='#444444' custom_font='#ffffff' btn_color_bg='theme-color' btn_custom_grad_direction='vertical' btn_custom_grad_1='#000000' btn_custom_grad_2='#ffffff' btn_custom_grad_3='' btn_custom_grad_opacity='0.7' btn_custom_bg='#444444' btn_color_bg_hover='theme-color-highlight' btn_custom_bg_hover='#444444' btn_color_font='theme-color' btn_custom_font='#ffffff' btn_color_font_hover='white' btn_custom_font_hover='#ffffff' border='' border_width='' border_width_sync='true' border_color='' border_radius='' border_radius_sync='true' box_shadow='' box_shadow_style='0px,0px,0px,0px' box_shadow_color='' hover_opacity='' sonar_effect_effect='' sonar_effect_color='' sonar_effect_duration='1' sonar_effect_scale='' sonar_effect_opac='0.5' element_template='' one_element_template='' av_uid='av-m1em5tdj' sc_version='1.0']\r\n[\/av_buttonrow]\r\n\r\n[av_heading heading='Sprzeda\u017c Polska' tag='h3' style='' subheading_active='' show_icon='' icon='ue800' font='entypo-fontello' size='' av-desktop-font-size-title='' av-medium-font-size-title='' av-small-font-size-title='' av-mini-font-size-title='' subheading_size='' av-desktop-font-size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' icon_size='' av-desktop-font-size-1='' av-medium-font-size-1='' av-small-font-size-1='' av-mini-font-size-1='' color='' custom_font='' subheading_color='' seperator_color='' icon_color='' margin='' margin_sync='true' av-desktop-margin='' av-desktop-margin_sync='true' av-medium-margin='' av-medium-margin_sync='true' av-small-margin='' av-small-margin_sync='true' av-mini-margin='' av-mini-margin_sync='true' headline_padding='' headline_padding_sync='true' av-desktop-headline_padding='' av-desktop-headline_padding_sync='true' av-medium-headline_padding='' av-medium-headline_padding_sync='true' av-small-headline_padding='' av-small-headline_padding_sync='true' av-mini-headline_padding='' av-mini-headline_padding_sync='true' padding='10' av-desktop-padding='' av-medium-padding='' av-small-padding='' av-mini-padding='' icon_padding='10' av-desktop-icon_padding='' av-medium-icon_padding='' av-small-icon_padding='' av-mini-icon_padding='' link='' link_target='' title_attr='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-26rf38' sc_version='1.0' admin_preview_bg=''][\/av_heading]\r\n\r\n[av_textblock fold_type='' fold_height='' fold_more='Weiterlesen' fold_less='Read less' fold_text_style='' fold_btn_align='' textblock_styling_align='' textblock_styling='' textblock_styling_gap='' textblock_styling_mobile='' size='' av-desktop-font-size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' font_color='' color='' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' fold_timer='' z_index_fold='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-1z0hx3' sc_version='1.0' admin_preview_bg='']\r\nSkontaktuj si\u0119 z naszym zespo\u0142em sprzeda\u017cy, je\u015bli chcesz dowiedzie\u0107 si\u0119 wi\u0119cej o naszych rozwi\u0105zaniach!\r\n[\/av_textblock]\r\n\r\n[av_buttonrow alignment='left' button_spacing='5' button_spacing_unit='px' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' text-padding='' text-padding_sync='true' av-desktop-text-padding='' av-desktop-text-padding_sync='true' av-medium-text-padding='' av-medium-text-padding_sync='true' av-small-text-padding='' av-small-text-padding_sync='true' av-mini-text-padding='' av-mini-text-padding_sync='true' alb_description='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-m1em7783' sc_version='1.0' admin_preview_bg='']\r\n[av_buttonrow_item label='biuro@resqmed.pl' icon_select='yes' icon='ue921' font='infinitt-icons' link='manually,sales@infinitteu.com' link_target='' size='small' label_display='' title_attr='' size-text='' av-desktop-font-size-text='' av-medium-font-size-text='' av-small-font-size-text='' av-mini-font-size-text='' btn-padding='' btn-padding_sync='true' av-desktop-btn-padding='' av-desktop-btn-padding_sync='true' av-medium-btn-padding='' av-medium-btn-padding_sync='true' av-small-btn-padding='' av-small-btn-padding_sync='true' av-mini-btn-padding='' av-mini-btn-padding_sync='true' color_options='' color='light' custom_bg='#444444' custom_font='#ffffff' btn_color_bg='theme-color' btn_custom_grad_direction='vertical' btn_custom_grad_1='#000000' btn_custom_grad_2='#ffffff' btn_custom_grad_3='' btn_custom_grad_opacity='0.7' btn_custom_bg='#444444' btn_color_bg_hover='theme-color-highlight' btn_custom_bg_hover='#444444' btn_color_font='theme-color' btn_custom_font='#ffffff' btn_color_font_hover='white' btn_custom_font_hover='#ffffff' border='' border_width='' border_width_sync='true' border_color='' border_radius='' border_radius_sync='true' box_shadow='' box_shadow_style='0px,0px,0px,0px' box_shadow_color='' hover_opacity='' sonar_effect_effect='' sonar_effect_color='' sonar_effect_duration='1' sonar_effect_scale='' sonar_effect_opac='0.5' element_template='' one_element_template='' av_uid='av-m1em6zgh' sc_version='1.0']\r\n[av_buttonrow_item label='+48 663 336 962' icon_select='yes' icon='ue916' font='infinitt-icons' link='manually,tel:+4969583000300' link_target='' size='small' label_display='' title_attr='' size-text='' av-desktop-font-size-text='' av-medium-font-size-text='' av-small-font-size-text='' av-mini-font-size-text='' btn-padding='' btn-padding_sync='true' av-desktop-btn-padding='' av-desktop-btn-padding_sync='true' av-medium-btn-padding='' av-medium-btn-padding_sync='true' av-small-btn-padding='' av-small-btn-padding_sync='true' av-mini-btn-padding='' av-mini-btn-padding_sync='true' color_options='' color='light' custom_bg='#444444' custom_font='#ffffff' btn_color_bg='theme-color' btn_custom_grad_direction='vertical' btn_custom_grad_1='#000000' btn_custom_grad_2='#ffffff' btn_custom_grad_3='' btn_custom_grad_opacity='0.7' btn_custom_bg='#444444' btn_color_bg_hover='theme-color-highlight' btn_custom_bg_hover='#444444' btn_color_font='theme-color' btn_custom_font='#ffffff' btn_color_font_hover='white' btn_custom_font_hover='#ffffff' border='' border_width='' border_width_sync='true' border_color='' border_radius='' border_radius_sync='true' box_shadow='' box_shadow_style='0px,0px,0px,0px' box_shadow_color='' hover_opacity='' sonar_effect_effect='' sonar_effect_color='' sonar_effect_duration='1' sonar_effect_scale='' sonar_effect_opac='0.5' element_template='' one_element_template='' av_uid='av-m1em762y' sc_version='1.0']\r\n[\/av_buttonrow]\r\n\r\n[av_heading heading='Sprzeda\u017c Europa' tag='h3' style='' subheading_active='' show_icon='' icon='ue800' font='entypo-fontello' size='' av-desktop-font-size-title='' av-medium-font-size-title='' av-small-font-size-title='' av-mini-font-size-title='' subheading_size='' av-desktop-font-size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' icon_size='' av-desktop-font-size-1='' av-medium-font-size-1='' av-small-font-size-1='' av-mini-font-size-1='' color='' custom_font='' subheading_color='' seperator_color='' icon_color='' margin='' margin_sync='true' av-desktop-margin='' av-desktop-margin_sync='true' av-medium-margin='' av-medium-margin_sync='true' av-small-margin='' av-small-margin_sync='true' av-mini-margin='' av-mini-margin_sync='true' headline_padding='' headline_padding_sync='true' av-desktop-headline_padding='' av-desktop-headline_padding_sync='true' av-medium-headline_padding='' av-medium-headline_padding_sync='true' av-small-headline_padding='' av-small-headline_padding_sync='true' av-mini-headline_padding='' av-mini-headline_padding_sync='true' padding='10' av-desktop-padding='' av-medium-padding='' av-small-padding='' av-mini-padding='' icon_padding='10' av-desktop-icon_padding='' av-medium-icon_padding='' av-small-icon_padding='' av-mini-icon_padding='' link='' link_target='' title_attr='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-lz6y9uwb' sc_version='1.0' admin_preview_bg=''][\/av_heading]\r\n\r\n[av_textblock fold_type='' fold_height='' fold_more='Weiterlesen' fold_less='Read less' fold_text_style='' fold_btn_align='' textblock_styling_align='' textblock_styling='' textblock_styling_gap='' textblock_styling_mobile='' size='' av-desktop-font-size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' font_color='' color='' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' fold_timer='' z_index_fold='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-240lzo' sc_version='1.0' admin_preview_bg='']\r\nSkontaktuj si\u0119 z naszym zespo\u0142em sprzeda\u017cy, je\u015bli chcesz dowiedzie\u0107 si\u0119 wi\u0119cej o naszych rozwi\u0105zaniach!\r\n[\/av_textblock]\r\n\r\n[av_buttonrow alignment='left' button_spacing='5' button_spacing_unit='px' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' text-padding='' text-padding_sync='true' av-desktop-text-padding='' av-desktop-text-padding_sync='true' av-medium-text-padding='' av-medium-text-padding_sync='true' av-small-text-padding='' av-small-text-padding_sync='true' av-mini-text-padding='' av-mini-text-padding_sync='true' alb_description='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-ly5rqaz2' sc_version='1.0' admin_preview_bg='']\r\n[av_buttonrow_item label='sales(at)infinitteu.com' icon_select='yes' icon='ue921' font='infinitt-icons' link='manually,sales@infinitteu.com' link_target='' size='small' label_display='' title_attr='' size-text='' av-desktop-font-size-text='' av-medium-font-size-text='' av-small-font-size-text='' av-mini-font-size-text='' btn-padding='' btn-padding_sync='true' av-desktop-btn-padding='' av-desktop-btn-padding_sync='true' av-medium-btn-padding='' av-medium-btn-padding_sync='true' av-small-btn-padding='' av-small-btn-padding_sync='true' av-mini-btn-padding='' av-mini-btn-padding_sync='true' color_options='' color='light' custom_bg='#444444' custom_font='#ffffff' btn_color_bg='theme-color' btn_custom_grad_direction='vertical' btn_custom_grad_1='#000000' btn_custom_grad_2='#ffffff' btn_custom_grad_3='' btn_custom_grad_opacity='0.7' btn_custom_bg='#444444' btn_color_bg_hover='theme-color-highlight' btn_custom_bg_hover='#444444' btn_color_font='theme-color' btn_custom_font='#ffffff' btn_color_font_hover='white' btn_custom_font_hover='#ffffff' border='' border_width='' border_width_sync='true' border_color='' border_radius='' border_radius_sync='true' box_shadow='' box_shadow_style='0px,0px,0px,0px' box_shadow_color='' hover_opacity='' sonar_effect_effect='' sonar_effect_color='' sonar_effect_duration='1' sonar_effect_scale='' sonar_effect_opac='0.5' element_template='' one_element_template='' av_uid='av-ly5rqak0' sc_version='1.0']\r\n[av_buttonrow_item label='+49 (0)69 583 000-200' icon_select='yes' icon='ue916' font='infinitt-icons' link='manually,tel:+4969583000300' link_target='' size='small' label_display='' title_attr='' size-text='' av-desktop-font-size-text='' av-medium-font-size-text='' av-small-font-size-text='' av-mini-font-size-text='' btn-padding='' btn-padding_sync='true' av-desktop-btn-padding='' av-desktop-btn-padding_sync='true' av-medium-btn-padding='' av-medium-btn-padding_sync='true' av-small-btn-padding='' av-small-btn-padding_sync='true' av-mini-btn-padding='' av-mini-btn-padding_sync='true' color_options='' color='light' custom_bg='#444444' custom_font='#ffffff' btn_color_bg='theme-color' btn_custom_grad_direction='vertical' btn_custom_grad_1='#000000' btn_custom_grad_2='#ffffff' btn_custom_grad_3='' btn_custom_grad_opacity='0.7' btn_custom_bg='#444444' btn_color_bg_hover='theme-color-highlight' btn_custom_bg_hover='#444444' btn_color_font='theme-color' btn_custom_font='#ffffff' btn_color_font_hover='white' btn_custom_font_hover='#ffffff' border='' border_width='' border_width_sync='true' border_color='' border_radius='' border_radius_sync='true' box_shadow='' box_shadow_style='0px,0px,0px,0px' box_shadow_color='' hover_opacity='' sonar_effect_effect='' sonar_effect_color='' sonar_effect_duration='1' sonar_effect_scale='' sonar_effect_opac='0.5' element_template='' one_element_template='' av_uid='av-nt71g' sc_version='1.0' icon_hover='']\r\n[\/av_buttonrow]\r\n\r\n[av_heading heading='Prasa i marketing' tag='h3' style='' subheading_active='' show_icon='' icon='ue800' font='entypo-fontello' size='' av-desktop-font-size-title='' av-medium-font-size-title='' av-small-font-size-title='' av-mini-font-size-title='' subheading_size='' av-desktop-font-size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' icon_size='' av-desktop-font-size-1='' av-medium-font-size-1='' av-small-font-size-1='' av-mini-font-size-1='' color='' custom_font='' subheading_color='' seperator_color='' icon_color='' margin='' margin_sync='true' av-desktop-margin='' av-desktop-margin_sync='true' av-medium-margin='' av-medium-margin_sync='true' av-small-margin='' av-small-margin_sync='true' av-mini-margin='' av-mini-margin_sync='true' headline_padding='' headline_padding_sync='true' av-desktop-headline_padding='' av-desktop-headline_padding_sync='true' av-medium-headline_padding='' av-medium-headline_padding_sync='true' av-small-headline_padding='' av-small-headline_padding_sync='true' av-mini-headline_padding='' av-mini-headline_padding_sync='true' padding='10' av-desktop-padding='' av-medium-padding='' av-small-padding='' av-mini-padding='' icon_padding='10' av-desktop-icon_padding='' av-medium-icon_padding='' av-small-icon_padding='' av-mini-icon_padding='' link='' link_target='' title_attr='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-1hfq3o' sc_version='1.0' admin_preview_bg=''][\/av_heading]\r\n\r\n[av_buttonrow alignment='left' button_spacing='5' button_spacing_unit='px' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' text-padding='' text-padding_sync='true' av-desktop-text-padding='' av-desktop-text-padding_sync='true' av-medium-text-padding='' av-medium-text-padding_sync='true' av-small-text-padding='' av-small-text-padding_sync='true' av-mini-text-padding='' av-mini-text-padding_sync='true' alb_description='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-ly5rqiqz' sc_version='1.0' admin_preview_bg='']\r\n[av_buttonrow_item label='marketing(at)infinitteu.com' icon_select='yes' icon='ue921' font='infinitt-icons' link='manually,marketing@infinitteu.com' link_target='' size='small' label_display='' title_attr='' size-text='' av-desktop-font-size-text='' av-medium-font-size-text='' av-small-font-size-text='' av-mini-font-size-text='' btn-padding='' btn-padding_sync='true' av-desktop-btn-padding='' av-desktop-btn-padding_sync='true' av-medium-btn-padding='' av-medium-btn-padding_sync='true' av-small-btn-padding='' av-small-btn-padding_sync='true' av-mini-btn-padding='' av-mini-btn-padding_sync='true' color_options='' color='light' custom_bg='#444444' custom_font='#ffffff' btn_color_bg='theme-color' btn_custom_grad_direction='vertical' btn_custom_grad_1='#000000' btn_custom_grad_2='#ffffff' btn_custom_grad_3='' btn_custom_grad_opacity='0.7' btn_custom_bg='#444444' btn_color_bg_hover='theme-color-highlight' btn_custom_bg_hover='#444444' btn_color_font='theme-color' btn_custom_font='#ffffff' btn_color_font_hover='white' btn_custom_font_hover='#ffffff' border='' border_width='' border_width_sync='true' border_color='' border_radius='' border_radius_sync='true' box_shadow='' box_shadow_style='0px,0px,0px,0px' box_shadow_color='' hover_opacity='' sonar_effect_effect='' sonar_effect_color='' sonar_effect_duration='1' sonar_effect_scale='' sonar_effect_opac='0.5' element_template='' one_element_template='' av_uid='av-ly5rqhv2' sc_version='1.0']\r\n[av_buttonrow_item label='+49 (0)69 583 000-200' icon_select='yes' icon='ue916' font='infinitt-icons' link='manually,tel:+4969583000300' link_target='' size='small' label_display='' title_attr='' size-text='' av-desktop-font-size-text='' av-medium-font-size-text='' av-small-font-size-text='' av-mini-font-size-text='' btn-padding='' btn-padding_sync='true' av-desktop-btn-padding='' av-desktop-btn-padding_sync='true' av-medium-btn-padding='' av-medium-btn-padding_sync='true' av-small-btn-padding='' av-small-btn-padding_sync='true' av-mini-btn-padding='' av-mini-btn-padding_sync='true' color_options='' color='light' custom_bg='#444444' custom_font='#ffffff' btn_color_bg='theme-color' btn_custom_grad_direction='vertical' btn_custom_grad_1='#000000' btn_custom_grad_2='#ffffff' btn_custom_grad_3='' btn_custom_grad_opacity='0.7' btn_custom_bg='#444444' btn_color_bg_hover='theme-color-highlight' btn_custom_bg_hover='#444444' btn_color_font='theme-color' btn_custom_font='#ffffff' btn_color_font_hover='white' btn_custom_font_hover='#ffffff' border='' border_width='' border_width_sync='true' border_color='' border_radius='' border_radius_sync='true' box_shadow='' box_shadow_style='0px,0px,0px,0px' box_shadow_color='' hover_opacity='' sonar_effect_effect='' sonar_effect_color='' sonar_effect_duration='1' sonar_effect_scale='' sonar_effect_opac='0.5' element_template='' one_element_template='' av_uid='av-d3l3g' sc_version='1.0' icon_hover='']\r\n[\/av_buttonrow]\r\n\r\n[av_heading heading='Administracja' tag='h3' style='' subheading_active='' show_icon='' icon='ue800' font='entypo-fontello' size='' av-desktop-font-size-title='' av-medium-font-size-title='' av-small-font-size-title='' av-mini-font-size-title='' subheading_size='' av-desktop-font-size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' icon_size='' av-desktop-font-size-1='' av-medium-font-size-1='' av-small-font-size-1='' av-mini-font-size-1='' color='' custom_font='' subheading_color='' seperator_color='' icon_color='' margin='' margin_sync='true' av-desktop-margin='' av-desktop-margin_sync='true' av-medium-margin='' av-medium-margin_sync='true' av-small-margin='' av-small-margin_sync='true' av-mini-margin='' av-mini-margin_sync='true' headline_padding='' headline_padding_sync='true' av-desktop-headline_padding='' av-desktop-headline_padding_sync='true' av-medium-headline_padding='' av-medium-headline_padding_sync='true' av-small-headline_padding='' av-small-headline_padding_sync='true' av-mini-headline_padding='' av-mini-headline_padding_sync='true' padding='10' av-desktop-padding='' av-medium-padding='' av-small-padding='' av-mini-padding='' icon_padding='10' av-desktop-icon_padding='' av-medium-icon_padding='' av-small-icon_padding='' av-mini-icon_padding='' link='' link_target='' title_attr='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-prkzo' sc_version='1.0' admin_preview_bg=''][\/av_heading]\r\n\r\n[av_buttonrow alignment='left' button_spacing='5' button_spacing_unit='px' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' text-padding='' text-padding_sync='true' av-desktop-text-padding='' av-desktop-text-padding_sync='true' av-medium-text-padding='' av-medium-text-padding_sync='true' av-small-text-padding='' av-small-text-padding_sync='true' av-mini-text-padding='' av-mini-text-padding_sync='true' alb_description='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-ly5rqq3h' sc_version='1.0' admin_preview_bg='']\r\n[av_buttonrow_item label='info(at)infinitteu.com' icon_select='yes' icon='ue921' font='infinitt-icons' link='manually,info@infinitteu.com' link_target='' size='small' label_display='' title_attr='' size-text='' av-desktop-font-size-text='' av-medium-font-size-text='' av-small-font-size-text='' av-mini-font-size-text='' btn-padding='' btn-padding_sync='true' av-desktop-btn-padding='' av-desktop-btn-padding_sync='true' av-medium-btn-padding='' av-medium-btn-padding_sync='true' av-small-btn-padding='' av-small-btn-padding_sync='true' av-mini-btn-padding='' av-mini-btn-padding_sync='true' color_options='' color='light' custom_bg='#444444' custom_font='#ffffff' btn_color_bg='theme-color' btn_custom_grad_direction='vertical' btn_custom_grad_1='#000000' btn_custom_grad_2='#ffffff' btn_custom_grad_3='' btn_custom_grad_opacity='0.7' btn_custom_bg='#444444' btn_color_bg_hover='theme-color-highlight' btn_custom_bg_hover='#444444' btn_color_font='theme-color' btn_custom_font='#ffffff' btn_color_font_hover='white' btn_custom_font_hover='#ffffff' border='' border_width='' border_width_sync='true' border_color='' border_radius='' border_radius_sync='true' box_shadow='' box_shadow_style='0px,0px,0px,0px' box_shadow_color='' hover_opacity='' sonar_effect_effect='' sonar_effect_color='' sonar_effect_duration='1' sonar_effect_scale='' sonar_effect_opac='0.5' element_template='' one_element_template='' av_uid='av-ly5rqpha' sc_version='1.0']\r\n[av_buttonrow_item label='+49 (0)69 583 000-200' icon_select='yes' icon='ue916' font='infinitt-icons' link='manually,tel:+4969583000300' link_target='' size='small' label_display='' title_attr='' size-text='' av-desktop-font-size-text='' av-medium-font-size-text='' av-small-font-size-text='' av-mini-font-size-text='' btn-padding='' btn-padding_sync='true' av-desktop-btn-padding='' av-desktop-btn-padding_sync='true' av-medium-btn-padding='' av-medium-btn-padding_sync='true' av-small-btn-padding='' av-small-btn-padding_sync='true' av-mini-btn-padding='' av-mini-btn-padding_sync='true' color_options='' color='light' custom_bg='#444444' custom_font='#ffffff' btn_color_bg='theme-color' btn_custom_grad_direction='vertical' btn_custom_grad_1='#000000' btn_custom_grad_2='#ffffff' btn_custom_grad_3='' btn_custom_grad_opacity='0.7' btn_custom_bg='#444444' btn_color_bg_hover='theme-color-highlight' btn_custom_bg_hover='#444444' btn_color_font='theme-color' btn_custom_font='#ffffff' btn_color_font_hover='white' btn_custom_font_hover='#ffffff' border='' border_width='' border_width_sync='true' border_color='' border_radius='' border_radius_sync='true' box_shadow='' box_shadow_style='0px,0px,0px,0px' box_shadow_color='' hover_opacity='' sonar_effect_effect='' sonar_effect_color='' sonar_effect_duration='1' sonar_effect_scale='' sonar_effect_opac='0.5' element_template='' one_element_template='' av_uid='av-9sfqs' sc_version='1.0' icon_hover='']\r\n[\/av_buttonrow]\r\n\r\n[av_hr class='invisible' icon_select='yes' icon='ue808' font='entypo-fontello' position='center' shadow='no-shadow' height='50' custom_border='av-border-thin' custom_width='50px' custom_margin_top='30px' custom_margin_bottom='30px' custom_border_color='' custom_icon_color='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-9qqsc' sc_version='1.0' admin_preview_bg='']\r\n\r\n[av_button label='do strony kontaktowej' icon_select='yes-right-icon' icon='ue87d' font='entypo-fontello' link='manually,https:\/\/infinitteurope.com\/pl\/skontaktuj-sie-z-nami\/' link_target='' size='small' position='left' label_display='' title_attr='' size-text='' av-desktop-font-size-text='' av-medium-font-size-text='' av-small-font-size-text='' av-mini-font-size-text='' margin='' margin_sync='true' padding='' padding_sync='true' av-desktop-margin='' av-desktop-margin_sync='true' av-desktop-padding='' av-desktop-padding_sync='true' av-medium-margin='' av-medium-margin_sync='true' av-medium-padding='' av-medium-padding_sync='true' av-small-margin='' av-small-margin_sync='true' av-small-padding='' av-small-padding_sync='true' av-mini-margin='' av-mini-margin_sync='true' av-mini-padding='' av-mini-padding_sync='true' color_options='' color='light' custom_bg='#444444' custom_font='#ffffff' btn_color_bg='theme-color' btn_custom_grad_direction='vertical' btn_custom_grad_1='#000000' btn_custom_grad_2='#ffffff' btn_custom_grad_3='' btn_custom_grad_opacity='0.7' btn_custom_bg='#444444' btn_color_bg_hover='theme-color-highlight' btn_custom_bg_hover='#444444' btn_color_font='theme-color' btn_custom_font='#ffffff' btn_color_font_hover='white' btn_custom_font_hover='#ffffff' border='' border_width='' border_width_sync='true' border_color='' border_radius='' border_radius_sync='true' box_shadow='' box_shadow_style='0px,0px,0px,0px' box_shadow_color='' animation='' animation_duration='' animation_custom_bg_color='' animation_z_index_curtain='100' hover_opacity='' sonar_effect_effect='' sonar_effect_color='' sonar_effect_duration='1' sonar_effect_scale='' sonar_effect_opac='0.5' css_position='' css_position_location=',,,' css_position_z_index='' av-desktop-css_position='' av-desktop-css_position_location=',,,' av-desktop-css_position_z_index='' av-medium-css_position='' av-medium-css_position_location=',,,' av-medium-css_position_z_index='' av-small-css_position='' av-small-css_position_location=',,,' av-small-css_position_z_index='' av-mini-css_position='' av-mini-css_position_location=',,,' av-mini-css_position_z_index='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-lp8g4ew3' sc_version='1.0' admin_preview_bg='']\r\n\r\n[\/av_one_half][\/av_section]\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":-99,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5643","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RT PACS | INFINITT - infinitteurope<\/title>\n<meta name=\"description\" content=\"Elastyczny dost\u0119p do danych z radioterapii dzi\u0119ki INFINITT RT PACS \u2705 \u27a4 Zoptymalizuj radioterapi\u0119 ju\u017c teraz\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infinitteurope.com\/pl\/rt-pacs\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RT PACS | INFINITT - infinitteurope\" \/>\n<meta property=\"og:description\" content=\"Elastyczny dost\u0119p do danych z radioterapii dzi\u0119ki INFINITT RT PACS \u2705 \u27a4 Zoptymalizuj radioterapi\u0119 ju\u017c teraz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infinitteurope.com\/pl\/rt-pacs\/\" \/>\n<meta property=\"og:site_name\" content=\"infinitteurope\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-24T08:46:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/04\/Infinitt_rt-pacs_logo.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data1\" content=\"99 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/infinitteurope.com\\\/pl\\\/rt-pacs\\\/\",\"url\":\"https:\\\/\\\/infinitteurope.com\\\/pl\\\/rt-pacs\\\/\",\"name\":\"RT PACS | INFINITT - infinitteurope\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infinitteurope.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/infinitteurope.com\\\/pl\\\/rt-pacs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/infinitteurope.com\\\/pl\\\/rt-pacs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infinitteurope.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Infinitt_rt-pacs_logo.jpg\",\"datePublished\":\"2024-04-25T14:01:40+00:00\",\"dateModified\":\"2025-06-24T08:46:49+00:00\",\"description\":\"Elastyczny dost\u0119p do danych z radioterapii dzi\u0119ki INFINITT RT PACS \u2705 \u27a4 Zoptymalizuj radioterapi\u0119 ju\u017c teraz\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/infinitteurope.com\\\/pl\\\/rt-pacs\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/infinitteurope.com\\\/pl\\\/rt-pacs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/infinitteurope.com\\\/pl\\\/rt-pacs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/infinitteurope.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Infinitt_rt-pacs_logo.jpg\",\"contentUrl\":\"https:\\\/\\\/infinitteurope.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Infinitt_rt-pacs_logo.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/infinitteurope.com\\\/pl\\\/rt-pacs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/infinitteurope.com\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RT PACS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/infinitteurope.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/infinitteurope.com\\\/pl\\\/\",\"name\":\"infinitteurope\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/infinitteurope.com\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/infinitteurope.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/infinitteurope.com\\\/pl\\\/#organization\",\"name\":\"Infinitt Europe GmbH\",\"url\":\"https:\\\/\\\/infinitteurope.com\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/infinitteurope.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/infinitteurope.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ieu_logo_blue-bg-white.jpg\",\"contentUrl\":\"https:\\\/\\\/infinitteurope.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/ieu_logo_blue-bg-white.jpg\",\"width\":600,\"height\":600,\"caption\":\"Infinitt Europe GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/infinitteurope.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RT PACS | INFINITT - infinitteurope","description":"Elastyczny dost\u0119p do danych z radioterapii dzi\u0119ki INFINITT RT PACS \u2705 \u27a4 Zoptymalizuj radioterapi\u0119 ju\u017c teraz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infinitteurope.com\/pl\/rt-pacs\/","og_locale":"pl_PL","og_type":"article","og_title":"RT PACS | INFINITT - infinitteurope","og_description":"Elastyczny dost\u0119p do danych z radioterapii dzi\u0119ki INFINITT RT PACS \u2705 \u27a4 Zoptymalizuj radioterapi\u0119 ju\u017c teraz","og_url":"https:\/\/infinitteurope.com\/pl\/rt-pacs\/","og_site_name":"infinitteurope","article_modified_time":"2025-06-24T08:46:49+00:00","og_image":[{"url":"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/04\/Infinitt_rt-pacs_logo.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Szacowany czas czytania":"99 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/infinitteurope.com\/pl\/rt-pacs\/","url":"https:\/\/infinitteurope.com\/pl\/rt-pacs\/","name":"RT PACS | INFINITT - infinitteurope","isPartOf":{"@id":"https:\/\/infinitteurope.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infinitteurope.com\/pl\/rt-pacs\/#primaryimage"},"image":{"@id":"https:\/\/infinitteurope.com\/pl\/rt-pacs\/#primaryimage"},"thumbnailUrl":"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/04\/Infinitt_rt-pacs_logo.jpg","datePublished":"2024-04-25T14:01:40+00:00","dateModified":"2025-06-24T08:46:49+00:00","description":"Elastyczny dost\u0119p do danych z radioterapii dzi\u0119ki INFINITT RT PACS \u2705 \u27a4 Zoptymalizuj radioterapi\u0119 ju\u017c teraz","breadcrumb":{"@id":"https:\/\/infinitteurope.com\/pl\/rt-pacs\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infinitteurope.com\/pl\/rt-pacs\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/infinitteurope.com\/pl\/rt-pacs\/#primaryimage","url":"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/04\/Infinitt_rt-pacs_logo.jpg","contentUrl":"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/04\/Infinitt_rt-pacs_logo.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/infinitteurope.com\/pl\/rt-pacs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/infinitteurope.com\/pl\/"},{"@type":"ListItem","position":2,"name":"RT PACS"}]},{"@type":"WebSite","@id":"https:\/\/infinitteurope.com\/pl\/#website","url":"https:\/\/infinitteurope.com\/pl\/","name":"infinitteurope","description":"","publisher":{"@id":"https:\/\/infinitteurope.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infinitteurope.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/infinitteurope.com\/pl\/#organization","name":"Infinitt Europe GmbH","url":"https:\/\/infinitteurope.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/infinitteurope.com\/pl\/#\/schema\/logo\/image\/","url":"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/07\/ieu_logo_blue-bg-white.jpg","contentUrl":"https:\/\/infinitteurope.com\/wp-content\/uploads\/2024\/07\/ieu_logo_blue-bg-white.jpg","width":600,"height":600,"caption":"Infinitt Europe GmbH"},"image":{"@id":"https:\/\/infinitteurope.com\/pl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/infinitteurope.com\/pl\/wp-json\/wp\/v2\/pages\/5643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infinitteurope.com\/pl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/infinitteurope.com\/pl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/infinitteurope.com\/pl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infinitteurope.com\/pl\/wp-json\/wp\/v2\/comments?post=5643"}],"version-history":[{"count":1,"href":"https:\/\/infinitteurope.com\/pl\/wp-json\/wp\/v2\/pages\/5643\/revisions"}],"predecessor-version":[{"id":8088,"href":"https:\/\/infinitteurope.com\/pl\/wp-json\/wp\/v2\/pages\/5643\/revisions\/8088"}],"wp:attachment":[{"href":"https:\/\/infinitteurope.com\/pl\/wp-json\/wp\/v2\/media?parent=5643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}